[{"id":9772,"date":"2024-09-22T08:42:31","date_gmt":"2024-09-22T08:42:31","guid":{"rendered":"https:\/\/congress.lausanne.org\/?page_id=9772"},"modified":"2024-09-22T08:42:31","modified_gmt":"2024-09-22T08:42:31","slug":"songdo-convensia-carte","status":"publish","type":"page","link":"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/","title":{"rendered":"Songdo Convensia Carte"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/drive.google.com\/file\/d\/1x-asbSNzclZoZbGEeUBZiJYqaXsuVZ69\/view?usp=drive_link\" target=\"_blank\" rel=\"noreferrer noopener\">Carte T\u00e9l\u00e9chargeable<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:5%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"4000\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1.png\" alt=\"\" class=\"wp-image-9790\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1.png 2250w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1-169x300.png 169w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1-576x1024.png 576w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1-768x1365.png 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1-864x1536.png 864w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1-1152x2048.png 1152w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1-1400x2489.png 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1-1920x3413.png 1920w\" sizes=\"auto, (max-width: 2250px) 100vw, 2250px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:5%\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Navette<\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:5%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"4000\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-2.png\" alt=\"\" class=\"wp-image-9797\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-2.png 2250w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-2-169x300.png 169w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-2-576x1024.png 576w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-2-768x1365.png 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-2-864x1536.png 864w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-2-1152x2048.png 1152w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-2-1400x2489.png 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-2-1920x3413.png 1920w\" sizes=\"auto, (max-width: 2250px) 100vw, 2250px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:5%\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Navette<\/p>\n","protected":false},"author":20,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9772","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Songdo Convensia Carte - The Fourth Lausanne Congress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Songdo Convensia Carte - The Fourth Lausanne Congress\" \/>\n<meta property=\"og:description\" content=\"Navette\" \/>\n<meta property=\"og:url\" content=\"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/\" \/>\n<meta property=\"og:site_name\" content=\"The Fourth Lausanne Congress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/\",\"name\":\"Songdo Convensia Carte - The Fourth Lausanne Congress\",\"isPartOf\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1.png\",\"datePublished\":\"2024-09-22T08:42:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/#primaryimage\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1.png\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/congress.lausanne.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Songdo Convensia Carte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"name\":\"The Fourth Lausanne Congress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\",\"name\":\"The Fourth Lausanne Congress\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"width\":1477,\"height\":266,\"caption\":\"The Fourth Lausanne Congress\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Songdo Convensia Carte - The Fourth Lausanne Congress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/","og_locale":"fr_FR","og_type":"article","og_title":"Songdo Convensia Carte - The Fourth Lausanne Congress","og_description":"Navette","og_url":"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/","og_site_name":"The Fourth Lausanne Congress","og_image":[{"url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/","url":"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/","name":"Songdo Convensia Carte - The Fourth Lausanne Congress","isPartOf":{"@id":"https:\/\/congress.lausanne.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/#primaryimage"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/#primaryimage"},"thumbnailUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1.png","datePublished":"2024-09-22T08:42:31+00:00","breadcrumb":{"@id":"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/#primaryimage","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1.png","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/FR_Convensia-Map_Update-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/congress.lausanne.org\/fr\/songdo-convensia-carte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/congress.lausanne.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Songdo Convensia Carte"}]},{"@type":"WebSite","@id":"https:\/\/congress.lausanne.org\/fr\/#website","url":"https:\/\/congress.lausanne.org\/fr\/","name":"The Fourth Lausanne Congress","description":"","publisher":{"@id":"https:\/\/congress.lausanne.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/congress.lausanne.org\/fr\/#organization","name":"The Fourth Lausanne Congress","url":"https:\/\/congress.lausanne.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","width":1477,"height":266,"caption":"The Fourth Lausanne Congress"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/comments?post=9772"}],"version-history":[{"count":0,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9772\/revisions"}],"wp:attachment":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/media?parent=9772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":9906,"date":"2024-09-12T12:12:34","date_gmt":"2024-09-12T12:12:34","guid":{"rendered":"https:\/\/congress.lausanne.org\/?page_id=9906"},"modified":"2024-09-23T05:08:39","modified_gmt":"2024-09-23T05:08:39","slug":"satellite-site-host-information","status":"publish","type":"page","link":"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/","title":{"rendered":"Informations concernant les h\u00e9bergeurs de site satellite"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"5504\" height=\"2748\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined.png\" alt=\"Satellite Sites\" class=\"wp-image-903\" style=\"width:200px\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined.png 5504w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined-300x150.png 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined-1024x511.png 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined-768x383.png 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined-1536x767.png 1536w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined-2048x1023.png 2048w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined-1400x699.png 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined-1920x959.png 1920w\" sizes=\"auto, (max-width: 5504px) 100vw, 5504px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group is-horizontal is-content-justification-center is-layout-flex wp-container-core-group-is-layout-a0364c55 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:55%\">\n<h3 class=\"wp-block-heading\">Contenu du congr\u00e8s sur demande, pour les sites satellites<\/h3>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-default, text-divider\" style=\"background-color:#0003ff;color:#0003ff\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Si notre premi\u00e8re intention pour les sites satellites tournait autour <a href=\"https:\/\/lausanne.org\/accelerate\"><strong>d&rsquo;Acc\u00e9l\u00e9rer<\/strong><\/a>, une initiative post\u00e9rieure au congr\u00e8s dans le cadre de notre offre pour l&rsquo;apr\u00e8s-congr\u00e8s, nous voulons cependant aider ceux qui d\u00e9sirent beaucoup participer \u00e0 distance au Quatri\u00e8me congr\u00e8s de Lausanne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les h\u00e9bergeurs de site satellite auront acc\u00e8s sur demande \u00e0 biblioth\u00e8que vid\u00e9o des principales s\u00e9ances du congr\u00e8s<\/strong>. C&rsquo;est l\u00e0 que vous trouverez le contenu \u00e0 visionner dans votre groupe. Les s\u00e9ances seront disponibles quelques heures apr\u00e8s leur tenue \u00e0 Incheon, en Cor\u00e9e du Sud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous encourageons \u00e0 saisir cette occasion pour vous rassembler, r\u00e9fl\u00e9chir et planifier comment votre groupe interagira avec le Mouvement de Lausanne tant pendant qu&rsquo;apr\u00e8s le congr\u00e8s.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:45%\"><div class=\"wp-block-image wp-duotone-unset-1\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/03\/congress-web-sat-site-opportunity.jpg\" alt=\"Opportunity\" class=\"wp-image-2115\" style=\"width:510px;height:auto\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/03\/congress-web-sat-site-opportunity.jpg 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/03\/congress-web-sat-site-opportunity-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/03\/congress-web-sat-site-opportunity-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/03\/congress-web-sat-site-opportunity-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/03\/congress-web-sat-site-opportunity-768x768.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-black-color has-text-color has-background has-link-color wp-elements-d84d00f98fcffb0c58dbc354c0bffdb9 is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 32%\"><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading has-black-color has-text-color has-link-color wp-elements-897687f56133cce2d7dd3428682f8020\">Acc\u00e8s au contenu des vid\u00e9os<\/h4>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-default, text-divider is-style-wide\" style=\"background-color:#0003ff;color:#0003ff\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Pendant la semaine du congr\u00e8s, votre groupe peut suivre les s\u00e9ances pl\u00e9ni\u00e8res par l&rsquo;interm\u00e9diaire de la biblioth\u00e8que de vid\u00e9os \u00e0 la demande. Votre h\u00e9bergeur de site satellite recevra bient\u00f4t les instructions sur comment y acc\u00e9der.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/video-library-1024x1024.jpg\" alt=\"\" class=\"wp-image-9509 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/video-library-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/video-library-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/video-library-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/video-library-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/video-library.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:35% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/discussion-guides-1024x1024.jpg\" alt=\"\" class=\"wp-image-9516 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/discussion-guides-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/discussion-guides-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/discussion-guides-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/discussion-guides-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/discussion-guides.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading has-black-color has-text-color has-link-color wp-elements-37d936a9b4d911328beb1a422afea466\">Creusez plus profond\u00e9ment gr\u00e2ce aux guides de discussion<\/h4>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-default, text-divider\" style=\"background-color:#0003ff;color:#0003ff\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Pour aider \u00e0 des discussions plus riches au sein de votre groupe, utilisez les questions interactives concernant les s\u00e9ances pl\u00e9ni\u00e8res. Ces questions, centr\u00e9es sur le partage biblique, l&rsquo;interaction misiologique et les le\u00e7ons provenant de l&rsquo;\u00c9glise mondiale, encourageront une r\u00e9flex`ion et un apprentissage plus profonds.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/drive.google.com\/file\/d\/1sduj-jrr45JHXqPYwpEgv3sIE15JHMbb\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9l\u00e9charger le PDF<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>D\u00e9roul\u00e9 du programme<\/strong><\/h3>\n\n\n\n<div style=\"position: relative; width: 100%; height: 0; padding-top: 56.2500%;\n padding-bottom: 0; box-shadow: 0 2px 8px 0 rgba(63,69,81,0.16); margin-top: 1.6em; margin-bottom: 0.9em; overflow: hidden;\n border-radius: 8px; will-change: transform;\">\n  <iframe loading=\"lazy\" style=\"position: absolute; width: 100%; height: 100%; top: 0; left: 0; border: none; padding: 0;margin: 0;\"\n    src=\"https:&#x2F;&#x2F;www.canva.com&#x2F;design&#x2F;DAGQd7pyvRY&#x2F;0ZdGSyHvjrELMo97wCu4nQ&#x2F;view?embed\" allowfullscreen=\"allowfullscreen\" allow=\"fullscreen\">\n  <\/iframe>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-text-color has-background has-link-color wp-elements-0d894c0a6df1378a583366f627cd3a0c is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"color:#1a1a1a;background-color:#1a1a1a\">\n<div class=\"wp-block-column has-white-color has-text-color has-background has-link-color wp-elements-a4dae6e4482ca96376b8ab7588458725 is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#1a1a1a;flex-basis:100%\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<h4 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-feb84324f612c20217c7283d1ba770f5\"><strong>Contact<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez besoin d&rsquo;aide ou si vous avez des questions, veuillez contacter <a href=\"mailto:remis@lausanne.org\">Ryan Emis<\/a> ou <a href=\"mailto:adruckemiller@lausanne.org\">Alison Druckemiller<\/a>. <\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Contenu du congr\u00e8s sur demande, pour les sites satellites Si notre premi\u00e8re intention pour les sites satellites tournait autour d&rsquo;Acc\u00e9l\u00e9rer, une initiative post\u00e9rieure au congr\u00e8s dans le cadre de notre offre pour l&rsquo;apr\u00e8s-congr\u00e8s, nous voulons cependant aider ceux qui d\u00e9sirent beaucoup participer \u00e0 distance au Quatri\u00e8me congr\u00e8s de Lausanne&#8230;.<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9906","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Informations concernant les h\u00e9bergeurs de site satellite - The Fourth Lausanne Congress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informations concernant les h\u00e9bergeurs de site satellite - The Fourth Lausanne Congress\" \/>\n<meta property=\"og:description\" content=\"Contenu du congr\u00e8s sur demande, pour les sites satellites Si notre premi\u00e8re intention pour les sites satellites tournait autour d&rsquo;Acc\u00e9l\u00e9rer, une initiative post\u00e9rieure au congr\u00e8s dans le cadre de notre offre pour l&rsquo;apr\u00e8s-congr\u00e8s, nous voulons cependant aider ceux qui d\u00e9sirent beaucoup participer \u00e0 distance au Quatri\u00e8me congr\u00e8s de Lausanne....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/\" \/>\n<meta property=\"og:site_name\" content=\"The Fourth Lausanne Congress\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-23T05:08:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/\",\"name\":\"Informations concernant les h\u00e9bergeurs de site satellite - The Fourth Lausanne Congress\",\"isPartOf\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined.png\",\"datePublished\":\"2024-09-12T12:12:34+00:00\",\"dateModified\":\"2024-09-23T05:08:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/#primaryimage\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined.png\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/congress.lausanne.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informations concernant les h\u00e9bergeurs de site satellite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"name\":\"The Fourth Lausanne Congress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\",\"name\":\"The Fourth Lausanne Congress\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"width\":1477,\"height\":266,\"caption\":\"The Fourth Lausanne Congress\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informations concernant les h\u00e9bergeurs de site satellite - The Fourth Lausanne Congress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/","og_locale":"fr_FR","og_type":"article","og_title":"Informations concernant les h\u00e9bergeurs de site satellite - The Fourth Lausanne Congress","og_description":"Contenu du congr\u00e8s sur demande, pour les sites satellites Si notre premi\u00e8re intention pour les sites satellites tournait autour d&rsquo;Acc\u00e9l\u00e9rer, une initiative post\u00e9rieure au congr\u00e8s dans le cadre de notre offre pour l&rsquo;apr\u00e8s-congr\u00e8s, nous voulons cependant aider ceux qui d\u00e9sirent beaucoup participer \u00e0 distance au Quatri\u00e8me congr\u00e8s de Lausanne....","og_url":"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/","og_site_name":"The Fourth Lausanne Congress","article_modified_time":"2024-09-23T05:08:39+00:00","og_image":[{"url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/","url":"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/","name":"Informations concernant les h\u00e9bergeurs de site satellite - The Fourth Lausanne Congress","isPartOf":{"@id":"https:\/\/congress.lausanne.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/#primaryimage"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/#primaryimage"},"thumbnailUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined.png","datePublished":"2024-09-12T12:12:34+00:00","dateModified":"2024-09-23T05:08:39+00:00","breadcrumb":{"@id":"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/#primaryimage","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined.png","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/02\/lausanne-congress-sat-icons-combined.png"},{"@type":"BreadcrumbList","@id":"https:\/\/congress.lausanne.org\/fr\/satellite-site-host-information\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/congress.lausanne.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Informations concernant les h\u00e9bergeurs de site satellite"}]},{"@type":"WebSite","@id":"https:\/\/congress.lausanne.org\/fr\/#website","url":"https:\/\/congress.lausanne.org\/fr\/","name":"The Fourth Lausanne Congress","description":"","publisher":{"@id":"https:\/\/congress.lausanne.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/congress.lausanne.org\/fr\/#organization","name":"The Fourth Lausanne Congress","url":"https:\/\/congress.lausanne.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","width":1477,"height":266,"caption":"The Fourth Lausanne Congress"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/comments?post=9906"}],"version-history":[{"count":0,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9906\/revisions"}],"wp:attachment":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/media?parent=9906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":9546,"date":"2024-09-12T01:50:27","date_gmt":"2024-09-12T01:50:27","guid":{"rendered":"https:\/\/congress.lausanne.org\/?page_id=9546"},"modified":"2024-09-21T01:30:14","modified_gmt":"2024-09-21T01:30:14","slug":"centre-de-decouverte-numerique","status":"publish","type":"page","link":"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/","title":{"rendered":"Centre de d\u00e9couverte num\u00e9rique"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<h2 class=\"wp-block-heading has-large-font-size\"><strong>Faire progresser le Mandat missionnaire dans un monde connect\u00e9<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Explorez le Centre de d\u00e9couverte num\u00e9rique au Quatri\u00e8me congr\u00e8s de Lausanne, o\u00f9 vous pourrez utiliser des outils num\u00e9riques, pratiques pour \u00e9laborer des strat\u00e9gies permettant de diffuser l&rsquo;Evangile \u00e0 l&rsquo;\u00e8re num\u00e9rique. Cet espace offre la possibilit\u00e9 d&rsquo;apprendre d&rsquo;organisations exp\u00e9riment\u00e9es et d&rsquo;examiner comment les progr\u00e8s num\u00e9riques fa\u00e7onnent l&rsquo;avenir du Mandat missionnaire.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--3\"><a class=\"wp-block-button__link wp-element-button\" href=\"#exhibitors\">Voir les pr\u00e9sentateurs<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--4\"><a class=\"wp-block-button__link wp-element-button\" href=\"#micro-talk-sched\">Voir le programme des micro-discussions<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--5\"><a class=\"wp-block-button__link wp-element-button\" href=\"#floor-plan\">Voir le plan de l&rsquo;exposition<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Digital Discovery Center\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ewhN_Hxinmk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-full <img src=&quot;path\/to\/your\/image.jpg&quot; class=&quot;full-width&quot; alt=&quot;Description of the image&quot;&gt;\"><img loading=\"lazy\" decoding=\"async\" width=\"2062\" height=\"825\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/ddc-landing-4.gif\" alt=\"\" class=\"wp-image-8853\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" id=\"exhibitors\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Pr\u00e9sentatrices<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9couvrez les exposants innovants du Centre de d\u00e9couverte num\u00e9rique, o\u00f9 des services chr\u00e9tiens, des organisations confessionnelles et des experts en technologie pr\u00e9sentent de nouveaux outils et strat\u00e9gies pour diffuser l&rsquo;\u00c9vangile \u00e0 l&rsquo;\u00e8re du num\u00e9rique.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.avodahconnect.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/avodah-logo.jpg\" alt=\"\" class=\"wp-image-8468 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/avodah-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/avodah-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/avodah-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.avodahconnect.com\" target=\"_blank\" rel=\"noreferrer noopener\">AvodahConnect<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">AvodahConnect, une division d&rsquo;Avodah Inc, s&rsquo;appuie sur une intelligence artificielle innovante pour r\u00e9volutionner la traduction de la Bible et des \u00c9glises. Notre technologie innovante permet de franchir les barri\u00e8res linguistiques, garantissant ainsi des traductions pr\u00e9cises et accessibles \u00e0 tous. En int\u00e9grant l&rsquo;IA, nous transformons les m\u00e9thodes de traduction traditionnelles, ce qui a un impact sur la diffusion de la parole et la compr\u00e9hension globale.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/FaithAssistant.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/bible-chat-ai-logo.jpg\" alt=\"\" class=\"wp-image-8475 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/bible-chat-ai-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/bible-chat-ai-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/bible-chat-ai-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/FaithAssistant.com\" target=\"_blank\" rel=\"noreferrer noopener\">BibleChat.Ai<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Faith Assistant et BibleChat.ai r\u00e9volutionnent l&rsquo;engagement chr\u00e9tien gr\u00e2ce \u00e0 une assistance pilot\u00e9e par l&rsquo;IA 24\/7. Faith Assistant am\u00e9liore les op\u00e9rations de l&rsquo;Eglise, permet de gagner du temps pour un minist\u00e8re \u00e0 fort impact et transforme la pr\u00e9dication en transformant les \u00c9glises en communaut\u00e9s chr\u00e9tiennes engag\u00e9es. BibleChat.ai offre un espace personnel et confidentiel pour l&rsquo;exploration des \u00c9critures et l&rsquo;accompagnement spirituel. Ensemble, ils offrent des solutions innovantes pour les \u00c9glises, les minist\u00e8res et les organisations m\u00e9diatiques, rendant l&rsquo;interaction bas\u00e9e sur la foi transparente, accessible et impactante dans le monde entier<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.bibleproject.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/bible-project-logo.jpg\" alt=\"\" class=\"wp-image-8482 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/bible-project-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/bible-project-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/bible-project-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.bibleproject.com\" target=\"_blank\" rel=\"noreferrer noopener\">BibleProject<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">BibleProject est une organisation \u00e0 but non lucratif, financ\u00e9e par le crowdfunding, qui produit des ressources gratuites telles que des vid\u00e9os, des podcasts, des articles et des cours pour aider les gens \u00e0 d\u00e9couvrir la Bible d&rsquo;une mani\u00e8re accessible et transformatrice. Pour ce faire, nous mettons en valeur l&rsquo;art litt\u00e9raire des \u00c9critures et retra\u00e7ons les th\u00e8mes bibliques cl\u00e9s de la Gen\u00e8se \u00e0 l&rsquo;Apocalypse.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/brilliancelabs.org\/bitcoin\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/brilliance-labs-logo.jpg\" alt=\"\" class=\"wp-image-8489 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/brilliance-labs-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/brilliance-labs-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/brilliance-labs-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/brilliancelabs.org\/bitcoin\" target=\"_blank\" rel=\"noreferrer noopener\">Brilliance Labs<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cadre de l&rsquo;initiative \u00ab Bitcoin for Missions \u00bb, la propagation de l&rsquo;\u00c9vangile est notre principal objectif. Nous visons \u00e0 identifier des acteurs missionnaires innovants et des partenaires nationaux travaillant dans des contextes financi\u00e8rement r\u00e9pressifs, \u00e0 leur faire d\u00e9couvrir le r\u00e9seau Bitcoin en tant que solution \u00e0 multiples facettes pour l&rsquo;autonomisation financi\u00e8re, et \u00e0 les accompagner dans le prototypage d&rsquo;outils et de solutions qui les aident \u00e0 remplir le Mandat Missionnaire.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/trucenter.co\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/cherith-analytics-logo.jpg\" alt=\"\" class=\"wp-image-8496 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/cherith-analytics-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/cherith-analytics-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/cherith-analytics-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/trucenter.co\" target=\"_blank\" rel=\"noreferrer noopener\">Cherith Analytics<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Cherith Analytics est une entreprise de la Fondation Impact, qui applique l&rsquo;IA et les technologies de pointe \u00e0 la foi, et d\u00e9ploie des outils BAM pour les missions. Nous proposons l&rsquo;un de ces produits, TruCenter, \u00e0 tous les participants au Congr\u00e8s. TruCenter aide les organisations \u00e0 engager leurs collaborateurs en reliant les motivations de Dieu \u00e0 leur travail, \u00e0 leurs relations et aux opportunit\u00e9s qui s&rsquo;offrent \u00e0 eux. L&rsquo;\u00e9valuation est construite \u00e0 partir d&rsquo;histoires, r\u00e9v\u00e9lant votre \u00ab pourquoi \u00bb. Il s&rsquo;agit de la seule \u00e9valuation ax\u00e9e sur les motivations et adapt\u00e9e aux organisations fond\u00e9es sur la foi.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.cvglobal.co\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/cv-logo.jpg\" alt=\"\" class=\"wp-image-8503 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/cv-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/cv-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/cv-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.cvglobal.co\" target=\"_blank\" rel=\"noreferrer noopener\">Christian Vision (CV)<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Christian Vision (CV) est un minist\u00e8re chr\u00e9tien mondial dont la mission est de pr\u00e9senter J\u00e9sus aux gens et de les encourager \u00e0 devenir ses v\u00e9ritables disciples. Fond\u00e9 en 1988 par Lord Robert Edmiston, CV souhaite vivement servir et \u00e9quiper les chr\u00e9tiens et les \u00c9glises locales dans leurs efforts d&rsquo;\u00e9vang\u00e9lisation. Nous nous effor\u00e7ons d&rsquo;avoir un impact dans trois domaines cl\u00e9s : Faire d\u00e9couvrir J\u00e9sus aux gens ; mobiliser les chr\u00e9tiens pour \u00e9vang\u00e9liser ; et approvisionner l&rsquo;\u00c9glise en contenu num\u00e9rique gratuit et en connaissances.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/ComeandSeeFoundation.org\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/come-and-see-logo.jpg\" alt=\"\" class=\"wp-image-8510 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/come-and-see-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/come-and-see-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/come-and-see-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/ComeandSeeFoundation.org\" target=\"_blank\" rel=\"noreferrer noopener\">Come and See Foundation<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Come and See a pour mission de veiller \u00e0 ce que les sept saisons de The Chosen soient distribu\u00e9es dans le monde entier, traduites en 600 langues et gratuites pour tous. Du Michigan \u00e0 Madagascar, des gens rencontrent J\u00e9sus gr\u00e2ce \u00e0 The Chosen, qui ne les laisse pas tels qu&rsquo;ils \u00e9taient. Rejoignez-nous pour inviter un milliard de personnes \u00e0 trouver et \u00e0 suivre J\u00e9sus.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/creedle.de\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/creedle-io-logo.jpg\" alt=\"\" class=\"wp-image-8517 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/creedle-io-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/creedle-io-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/creedle-io-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/creedle.de\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\">creedle<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Nous voulons rassembler les forces des chr\u00e9tiens afin de rendre J\u00e9sus visible num\u00e9riquement. Nous rendons cela possible gr\u00e2ce \u00e0 des applications ax\u00e9es sur les besoins, les creedlec. Elles seront reli\u00e9es de mani\u00e8re centralis\u00e9e au sein du futur \u00e9cosyst\u00e8me num\u00e9rique par le biais du moteur de recherche creedle.io. Nous cr\u00e9ons un \u00ab super-\u00e9cosyst\u00e8me \u00bb qui peut relier les nombreuses initiatives d&rsquo;offres chr\u00e9tiennes pour atteindre les gens num\u00e9riquement.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.discipleiq.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/disciple-iq-logo.jpg\" alt=\"\" class=\"wp-image-8524 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/disciple-iq-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/disciple-iq-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/disciple-iq-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.discipleiq.com\" target=\"_blank\" rel=\"noreferrer noopener\">DiscipleIQ<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">DiscipleIQ est une plateforme polyvalente con\u00e7ue pour soutenir les \u00c9glises et les minist\u00e8res du monde entier dans l&rsquo;am\u00e9lioration du discipulat et de l&rsquo;engagement communautaire. Gr\u00e2ce \u00e0 son m\u00e9lange d&rsquo;analyses avanc\u00e9es, de parcours d&rsquo;apprentissage personnalis\u00e9s et d&rsquo;outils interactifs, DiscipleIQ aide les leaders \u00e0 se connecter avec leurs assembl\u00e9es de mani\u00e8re plus significative, en encourageant le d\u00e9veloppement spirituel dans diverses cultures. Qu&rsquo;il s&rsquo;agisse de guider de nouveaux croyants ou de renforcer la foi de membres de longue date, DiscipleIQ offre une solution globale pour un discipulat efficace.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.faithtech.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/faith-tech-logo.jpg\" alt=\"\" class=\"wp-image-8531 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/faith-tech-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/faith-tech-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/faith-tech-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.faithtech.com\" target=\"_blank\" rel=\"noreferrer noopener\">FaithTech<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">FaithTech existe pour voir un r\u00e9veil en J\u00e9sus \u00e9merger dans et \u00e0 travers la technologie en pratiquant un design technologique r\u00e9dempteur. Nous sommes une communaut\u00e9 mondiale pour les chr\u00e9tiens dans le domaine de la technologie afin de se connecter les uns aux autres et de construire ensemble. Nous utilisons notre cadre de d\u00e9veloppement technologique r\u00e9dempteur bas\u00e9 sur la Bible pour construire des produits ensemble dans la communaut\u00e9 afin d&rsquo;aider l&rsquo;\u00e9glise locale et les marginalis\u00e9s, et de faire avancer la propagation de l&rsquo;\u00c9vangile. Nous avons actuellement des communaut\u00e9s FaithTech qui se r\u00e9unissent dans 43 villes \u00e0 travers 18 pays dans le monde.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/disciple.tools\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/gospel-ambition-logo.jpg\" alt=\"\" class=\"wp-image-8538 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/gospel-ambition-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/gospel-ambition-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/gospel-ambition-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/disciple.tools\" target=\"_blank\" rel=\"noreferrer noopener\">Gospel Ambition (Disciple Tools)<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Gospel Ambition existe pour servir l&rsquo;\u00c9glise en multipliant les disciples ob\u00e9issants, en cr\u00e9ant et en donnant des outils et des formations multilingues pour accomplir le Mandat Missionnaire dans cette g\u00e9n\u00e9ration. Le logiciel open source Disciple.Tools stimule la collaboration, la clart\u00e9 et la fiabilit\u00e9 des mouvements de multiplication de disciples et d&rsquo;\u00c9glises. Disciple.Tools est la technologie de base qui alimente Zume Training (https:\/\/zume.training), Prayer Tools (https:\/\/prayer.tools), Prayer Global (https:\/\/prayer.global), et des centaines de minist\u00e8res dans le monde entier.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/gravityjack.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/gravity-jack-logo.jpg\" alt=\"\" class=\"wp-image-8545 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/gravity-jack-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/gravity-jack-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/gravity-jack-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/gravityjack.com\" target=\"_blank\" rel=\"noreferrer noopener\">Gravity Jack, Inc.<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Gravity Jack, la plus ancienne entreprise de RA des \u00c9tats-Unis (fond\u00e9e en 2009), peut se targuer de 15 ans de R&amp;D, de brevets cl\u00e9s c\u00e9d\u00e9s sous licence \u00e0 des g\u00e9ants de la technologie et d&rsquo;une liste de clients comprenant la NASA, Kraft et le minist\u00e8re am\u00e9ricain de la d\u00e9fense. Forte de son exp\u00e9rience dans le domaine des jeux, l&rsquo;entreprise s&rsquo;appr\u00eate \u00e0 r\u00e9volutionner les jeux de r\u00e9alit\u00e9 augment\u00e9e avec WarTribe of Binyamin. Notamment, les fondateurs Luke et Jennifer Richey ont consacr\u00e9 leur vie \u00e0 J\u00e9sus en 2019, consid\u00e9rant leur entreprise s\u00e9culaire comme un champ de mission pour infiltrer le territoire de l&rsquo;ennemi et r\u00e9pandre l&rsquo;\u00c9vangile.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/indigitous.org\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/indigitous-logo.jpg\" alt=\"\" class=\"wp-image-8552 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/indigitous-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/indigitous-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/indigitous-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/indigitous.org\" target=\"_blank\" rel=\"noreferrer noopener\">Indigitous<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Dans notre monde connect\u00e9 et num\u00e9rique, un mouvement mondial apporte l&rsquo;\u00c9vangile \u00e0 de nouvelles personnes, de nouveaux lieux et de nouveaux espaces.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.jesusfilm.org\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Jesus-film-project-logo.jpg\" alt=\"\" class=\"wp-image-8559 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Jesus-film-project-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Jesus-film-project-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Jesus-film-project-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/your.nextstep.is\/lausanne-jesus-film\" target=\"_blank\" rel=\"noreferrer noopener\">Jesus Film Project<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Le minist\u00e8re des m\u00e9dias chr\u00e9tiens permet \u00e0 des millions de personnes de rencontrer J\u00e9sus dans la langue de leur c\u0153ur. Nous offrons l&rsquo;un des moyens les plus puissants de vivre l&rsquo;histoire de Christ en la regardant se d\u00e9rouler \u00e0 l&rsquo;\u00e9cran. Nos films chr\u00e9tiens gratuits en ligne et nos outils de minist\u00e8re aident \u00e0 transmettre le message de l&rsquo;\u00c9vangile dans plus de 2 000 langues et ce chiffre ne cesse de cro\u00eetre.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/jesus.net\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Jesus-net-logo.jpg\" alt=\"\" class=\"wp-image-8566 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Jesus-net-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Jesus-net-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Jesus-net-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/jesus.net\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jesus.net<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Jesus.net conduit les internautes \u00e0 J\u00e9sus, \u00e0 un cheminement de foi et \u00e0 une communaut\u00e9 (locale).<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.joshuaproject.net\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Joshua-project-logo.jpg\" alt=\"\" class=\"wp-image-8573 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Joshua-project-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Joshua-project-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Joshua-project-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.joshuaproject.net\" target=\"_blank\" rel=\"noreferrer noopener\">Joshua Project<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">La vision du Projet Joshua est de voir Dieu glorifi\u00e9 par une abondance de disciples de Christ au sein de chaque groupe de population. Notre mission est de mettre en lumi\u00e8re les peuples et les lieux qui ont le moins d&rsquo;acc\u00e8s ou de r\u00e9ponse \u00e0 l&rsquo;Evangile afin que le Corps de Christ puisse prioriser ses efforts de pri\u00e8re et de mission.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/landofpromiseofficial.xyz\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/land-of-promise-logo.jpg\" alt=\"\" class=\"wp-image-8580 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/land-of-promise-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/land-of-promise-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/land-of-promise-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/landofpromiseofficial.xyz\" target=\"_blank\" rel=\"noreferrer noopener\">Land of Promise<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Nous construisons un serveur Minecraft chr\u00e9tien appel\u00e9 Land of Promise (LOP) pour engager les enfants de 7 \u00e0 16 ans. Nous combinons la joie du jeu avec les enseignements de la Parole de Dieu pour former les enfants et les jeunes d&rsquo;une mani\u00e8re amusante et interactive !<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/lausanne.org\/digital-ecosystem\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Lausanne-movement-logo.jpg\" alt=\"\" class=\"wp-image-8587 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Lausanne-movement-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Lausanne-movement-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/Lausanne-movement-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/lausanne.org\/digital-ecosystem\" target=\"_blank\" rel=\"noreferrer noopener\">Lausanne Digital Ecosystem<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Inspir\u00e9 par Actes 4, l&rsquo;\u00e9cosyst\u00e8me num\u00e9rique de Lausanne est une exploration visant \u00e0 acc\u00e9l\u00e9rer la collaboration mondiale et la maturation des disciples \u00e0 l&rsquo;\u00e9chelle mondiale gr\u00e2ce \u00e0 des actifs num\u00e9riques partag\u00e9s &#8211; contenu, donn\u00e9es, applications et communaut\u00e9s num\u00e9riques. L&rsquo;\u00e9cosyst\u00e8me vise \u00e0 unir l&rsquo;\u00c9glise par la collaboration et l&rsquo;impact mondial partag\u00e9, convaincus que nous sommes meilleurs ensemble. L&rsquo;\u00e9cosyst\u00e8me est construit par le groupe Gargantua (https:\/\/www.gargantua.llc\/), une entreprise technologique de pointe sp\u00e9cialis\u00e9e dans la strat\u00e9gie, l&rsquo;apprentissage automatique et les services d&rsquo;IA g\u00e9n\u00e9rative. Gargantua se sp\u00e9cialise dans la transformation d&rsquo;informations brutes et d\u00e9sordonn\u00e9es en ensembles de donn\u00e9es structur\u00e9s et propres qui alimentent les syst\u00e8mes d&rsquo;apprentissage automatique et les plateformes de contenu.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/www.24-7prayer.com\/resource\/lectio-365\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/24-7-prayer-logo.jpg\" alt=\"\" class=\"wp-image-8594 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/24-7-prayer-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/24-7-prayer-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/24-7-prayer-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/www.24-7prayer.com\/resource\/lectio-365\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lectio 365 (24-7 Prayer)<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Lectio 365 est la ressource de m\u00e9ditations quotidiennes du mouvement international de pri\u00e8re 24-7 et a \u00e9t\u00e9 lanc\u00e9e \u00e0 l&rsquo;Avent 2019. Lectio 365 s&rsquo;est rapidement d\u00e9velopp\u00e9 pour accompagner des centaines de milliers de personnes \u00e0 travers le monde \u00e0 commencer et terminer leur journ\u00e9e avec Dieu.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.thelightdao.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/light-dao-logo.jpg\" alt=\"\" class=\"wp-image-8601 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/light-dao-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/light-dao-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/light-dao-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.thelightdao.com\" target=\"_blank\" rel=\"noreferrer noopener\">Light DAO<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Lightdao est la premi\u00e8re plateforme chr\u00e9tienne de NFT qui g\u00e8re et vend des \u0153uvres d&rsquo;art num\u00e9riques ax\u00e9es sur la foi.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.lightinaction.org\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/light-in-action-logo.jpg\" alt=\"\" class=\"wp-image-8608 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/light-in-action-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/light-in-action-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/light-in-action-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.lightinaction.org\" target=\"_blank\" rel=\"noreferrer noopener\">Light in Action<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">En tirant parti de la capacit\u00e9 unique du film \u00e0 atteindre des r\u00e9gions ferm\u00e9es \u00e0 l&rsquo;\u00c9vangile, les personnes vivant dans des zones restreintes ont acc\u00e8s \u00e0 un contenu qui remet en question leur vision du monde. En exploitant le pouvoir de l&rsquo;histoire pour toucher le c\u0153ur et ouvrir l&rsquo;esprit, on cr\u00e9e une soif de v\u00e9rit\u00e9. En rendant l&rsquo;\u00c9vangile facilement accessible, ceux qui cherchent la v\u00e9rit\u00e9 peuvent trouver une nouvelle vie en J\u00e9sus.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.lighthouseaw.org\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/lighthouse-logo.jpg\" alt=\"\" class=\"wp-image-8615 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/lighthouse-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/lighthouse-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/lighthouse-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.lighthouseaw.org\" target=\"_blank\" rel=\"noreferrer noopener\">Lighthouse Arab World<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Les Arabes ont besoin d&rsquo;entendre l&rsquo;\u00c9vangile. Le monde arabe, o\u00f9 le christianisme est n\u00e9, n&rsquo;a qu&rsquo;un acc\u00e8s limit\u00e9 \u00e0 l&rsquo;\u00c9vangile. Lighthouse Arab World s&rsquo;efforce d&rsquo;atteindre les groupes de population mal desservis avec un contenu principalement en arabe, cr\u00e9\u00e9 par des personnes passionn\u00e9es par la connexion avec les esprits et les c\u0153urs arabes. Bas\u00e9s \u00e0 Beyrouth, avec des membres de l&rsquo;\u00e9quipe dans toute la r\u00e9gion et aux \u00c9tats-Unis, nous utilisons divers m\u00e9dias pour rendre le christianisme accessible et compr\u00e9hensible, malgr\u00e9 des d\u00e9fis tels que la pers\u00e9cution et la pr\u00e9sence limit\u00e9e des chr\u00e9tiens.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.logos.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/logos-bible-logo.jpg\" alt=\"\" class=\"wp-image-8622 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/logos-bible-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/logos-bible-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/logos-bible-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.logos.com\" target=\"_blank\" rel=\"noreferrer noopener\">Logos Bible Software<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Logos Bible Software est une entreprise technologique engag\u00e9e dans l&rsquo;\u00c9glise. Nous existons pour permettre aux croyants du monde entier d&rsquo;approfondir la Bible gr\u00e2ce \u00e0 la fusion de ressources d&rsquo;\u00e9tude biblique et d&rsquo;une technologie puissante. Et nous nous engageons \u00e0 accro\u00eetre la connaissance biblique et l&rsquo;accessibilit\u00e9 pour chaque chr\u00e9tien dans le monde entier. C&rsquo;est la vision derri\u00e8re tout ce que nous faisons, de notre plateforme d&rsquo;\u00e9tude biblique \u00e0 la technologie de l&rsquo;\u00c9glise et tout ce qui se trouve entre les deux.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/www.mii.global\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/media-impact-logo.jpg\" alt=\"\" class=\"wp-image-8629 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/media-impact-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/media-impact-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/media-impact-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/www.mii.global\/\" target=\"_blank\" rel=\"noreferrer noopener\">Media Impact International<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Chez MII, nous cr\u00e9ons et facilitons des chemins d&rsquo;espoir qui font passer les personnes en recherche d&rsquo;une pr\u00e9sentation num\u00e9rique de l&rsquo;\u00c9vangile \u00e0 une participation \u00e0 une communaut\u00e9 chr\u00e9tienne qui change leur vie, \u00e0 la fois en ligne et hors ligne, par laquelle les personnes en recherche deviennent des disciples multiplicateurs de J\u00e9sus-Christ \u00e0 travers des communaut\u00e9s de soutien qui leur donnent la vie. Nous y parvenons gr\u00e2ce \u00e0 des partenariats strat\u00e9giques avec plus de 300 minist\u00e8res dans 50 pays, en leur offrant une formation essentielle sur les m\u00e9dias num\u00e9riques et le minist\u00e8re, ainsi qu&rsquo;un soutien pratique en mati\u00e8re de marketing num\u00e9rique et de suivi.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/megavoice.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/megavoice-logo.jpg\" alt=\"\" class=\"wp-image-8636 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/megavoice-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/megavoice-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/megavoice-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/megavoice.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">MegaVoice<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">MegaVoice a vu le jour lors du deuxi\u00e8me congr\u00e8s de Lausanne \u00e0 Manille et, depuis plus de 35 ans, continue \u00e0 fournir des solutions innovantes pour permettre aux partenaires de remplir le Mandat Missionnaire avec des outils s\u00fbrs et fiables qui surmontent les barri\u00e8res de la langue, de la g\u00e9ographie, de la technologie, de l&rsquo;alphab\u00e9tisation, du genre et des st\u00e9r\u00e9otypes sociaux, et en particulier les personnes qui ne sont pas atteintes ou les moins atteintes.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.missionallabs.co\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/missional-labs-logo.jpg\" alt=\"\" class=\"wp-image-8643 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/missional-labs-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/missional-labs-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/missional-labs-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.missionallabs.co\" target=\"_blank\" rel=\"noreferrer noopener\">Missional Labs<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Missional Labs est un r\u00e9seau de startups pour l&rsquo;\u00c9glise mondiale, qui fait progresser les id\u00e9es, les leaders et les entreprises qui fa\u00e7onnent la mission du XXIe si\u00e8cle. Nous m\u00e9langeons le meilleur de la th\u00e9ologie, de la mission et de l&rsquo;entreprenariat pour lancer une nouvelle g\u00e9n\u00e9ration de minist\u00e8res innovants qui font progresser l&rsquo;impact de l&rsquo;\u00c9vangile dans tous les contextes.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.Network211.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/network-211-logo.jpg\" alt=\"\" class=\"wp-image-8650 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/network-211-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/network-211-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/network-211-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.Network211.com\" target=\"_blank\" rel=\"noreferrer noopener\">Network211<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Alors que les gens du monde entier continuent \u00e0 chercher sur Internet des r\u00e9ponses aux dilemmes de leur vie, ils offrent \u00e0 Network211 une porte ouverte sur leur c\u0153ur afin que nous puissions les aider \u00e0 d\u00e9couvrir et \u00e0 grandir dans leur cheminement avec Dieu.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/olivetech.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/olive-logo.jpg\" alt=\"\" class=\"wp-image-8657 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/olive-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/olive-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/olive-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/olivetech.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Olive Technology Limited<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Olive Technology, Inc est une soci\u00e9t\u00e9 mondiale de services informatiques et de conseil en technologie avec plus de 26 ans d&rsquo;exp\u00e9rience dans les services d&rsquo;application, les solutions d&rsquo;entreprise et les solutions de transformation num\u00e9rique \u00e0 travers les industries.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/prayercast.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/prayer-cast-logo.jpg\" alt=\"\" class=\"wp-image-8664 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/prayer-cast-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/prayer-cast-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/prayer-cast-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/prayercast.com\" target=\"_blank\" rel=\"noreferrer noopener\">Prayercast<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Prayercast active une pri\u00e8re pour les perdus qui change le monde. En tirant parti des arts avec des technologies et des m\u00e9dias innovants, nous cr\u00e9ons des ressources de pri\u00e8re artistiques et convaincantes qui guident le peuple de Dieu dans plus de 180 pays chaque mois. Le contenu de Prayercast est r\u00e9guli\u00e8rement utilis\u00e9 dans les m\u00e9ditations personnelles, les r\u00e9unions de pri\u00e8re, les cultes, les salles de classe, les conf\u00e9rences, les grands rassemblements de pri\u00e8re internationaux, et bien d&rsquo;autres choses encore.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/www.rightnowmedia.org\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/right-now-media-logo.jpg\" alt=\"\" class=\"wp-image-8671 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/right-now-media-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/right-now-media-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/right-now-media-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/www.rightnowmedia.org\" target=\"_blank\" rel=\"noreferrer noopener\">Rightnow Media<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Nous croyons que la mission de l&rsquo;\u00c9glise est importante. Tout ce que nous faisons \u00e0 RightNow Media est enracin\u00e9 dans la promesse de J\u00e9sus que Dieu utilisera son peuple pour changer le monde. Nous sommes ici pour servir l&rsquo;\u00c9glise. Nous fournissons aux chr\u00e9tiens du monde entier des ressources qui les inciteront \u00e0 d\u00e9fendre la mission que J\u00e9sus a confi\u00e9e \u00e0 son peuple, \u00e0 savoir faire de toutes les nations des disciples. Dieu nous appelle \u00e0 centrer notre vie sur lui plut\u00f4t que sur nous-m\u00eames. Que ce soit \u00e0 l&rsquo;\u00c9glise, sur le lieu de travail ou \u00e0 la maison, nous voulons voir des disciples de J\u00e9sus aimer Dieu et aimer les autres. D\u00e9couvrez la plus grande biblioth\u00e8que personnalisable au monde de ressources vid\u00e9o bibliques pour chaque personne de votre \u00c9glise ou de votre minist\u00e8re. \u00c9quipez et inspirez vos \u00e9quipes au-del\u00e0 du dimanche. RightNow Media est une biblioth\u00e8que de streaming mondiale avec plus de 25 000 vid\u00e9os d&rsquo;\u00e9tudes bibliques chr\u00e9tiennes pour les dirigeants d&rsquo;\u00e9glise \u00e0 partager avec leurs \u00e9quipes et leurs petits groupes. L&rsquo;application et le contenu vid\u00e9o prennent en charge 13 langues et desservent plus de 25 000 \u00c9glises dans le monde. Aidez votre \u00e9quipe \u00e0 s&rsquo;\u00e9panouir dans tous les domaines de la vie avec des ressources vid\u00e9o \u00e0 la demande sur le leadership, le d\u00e9veloppement professionnel et les soins personnels. Rejoignez des milliers de participants \u00e0 l&rsquo;un de nos \u00e9v\u00e9nements strat\u00e9giques con\u00e7us pour vous aider \u00e0 vivre votre mission, quelle que soit votre vocation ou votre situation g\u00e9ographique. RightNow Ministries op\u00e8re sous la gr\u00e2ce du Dieu tout-puissant. Nous servons des \u00c9glises locales qui repr\u00e9sentent diverses traditions et d\u00e9nominations.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/www.saltandlight.community\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/salt-light-logo.jpg\" alt=\"\" class=\"wp-image-8678 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/salt-light-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/salt-light-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/salt-light-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/www.saltandlight.community\/\" target=\"_blank\" rel=\"noreferrer noopener\">Salt + Light<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Les gens cherchent d\u00e9sesp\u00e9r\u00e9ment de l&rsquo;aide pour les luttes de la vie et l&rsquo;une des meilleures sources de sagesse est les croyants dans l&rsquo;\u00e9glise locale. L&rsquo;un de nos projets est une application de messagerie audio pour les petits groupes. L&rsquo;application favorise la pri\u00e8re et la discussion en encourageant intentionnellement des liens plus forts. Notre \u00e9quipe construit activement des produits \u00e0 l&rsquo;intersection des communaut\u00e9s, des familles et de l&rsquo;\u00e9vang\u00e9lisation.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/searchforjesus.net\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/search-for-Jesus-logo.jpg\" alt=\"\" class=\"wp-image-8685 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/search-for-Jesus-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/search-for-Jesus-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/search-for-Jesus-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/searchforjesus.net\" target=\"_blank\" rel=\"noreferrer noopener\">Search For Jesus<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Search for Jesus utilise internet pour partager l&rsquo;\u00c9vangile dans le monde entier en 7 langues. Gr\u00e2ce aux sites web d&rsquo;\u00e9vang\u00e9lisation et aux pages de m\u00e9dias sociaux du minist\u00e8re, des personnes de tous horizons voient et entendent un message clair sur l&rsquo;\u00c9vangile. Des b\u00e9n\u00e9voles form\u00e9s sont pr\u00eats \u00e0 r\u00e9pondre \u00e0 leurs questions spirituelles, \u00e0 les orienter vers Christ et \u00e0 les aider \u00e0 grandir dans leur foi.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/sil.org\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/sil-logo.jpg\" alt=\"\" class=\"wp-image-8692 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/sil-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/sil-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/sil-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/sil.org\" target=\"_blank\" rel=\"noreferrer noopener\">SIL International<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">SIL International s&rsquo;associe aux communaut\u00e9s linguistiques locales pour d\u00e9velopper des solutions linguistiques qui favorisent l&rsquo;\u00e9panouissement. Inspir\u00e9s par l&rsquo;amour de Dieu, nous plaidons, renfor\u00e7ons les capacit\u00e9s et travaillons avec diligence pour que les gens puissent s&rsquo;engager dans les \u00c9critures, poursuivre un d\u00e9veloppement significatif et acc\u00e9der \u00e0 l&rsquo;\u00e9ducation dans les langues qu&rsquo;ils appr\u00e9cient le plus. Ensemble, nous voyons des vies transform\u00e9es et des communaut\u00e9s en plein essor.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/www.somagames.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/soma-games-logo.jpg\" alt=\"\" class=\"wp-image-8699 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/soma-games-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/soma-games-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/soma-games-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/www.somagames.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Soma Games<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Soma a \u00e9t\u00e9 cr\u00e9\u00e9 en r\u00e9ponse directe \u00e0 ce que nous appelons le \u00ab coup de pouce de Dieu \u00bb. Un jour, un article est apparu dans les journaux, parlant d&rsquo;une nouvelle tendance, les jeux vid\u00e9o chr\u00e9tiens. Le lien menait \u00e0 la Christian Game Developers Conference (conf\u00e9rence des d\u00e9veloppeurs de jeux chr\u00e9tiens). L&rsquo;inscription \u00e0 l&rsquo;\u00e9v\u00e9nement a d\u00e9bouch\u00e9 (en l&rsquo;espace de 10 minutes) sur une invitation \u00e0 se rendre \u00e0 Boston et \u00e0 passer \u00e0 la t\u00e9l\u00e9vision &#8211; pour parler des jeux vid\u00e9o chr\u00e9tiens et de la fa\u00e7on dont cette tendance s&rsquo;oppose \u00e0 des jeux tels que Grand Theft Auto. Bien que Soma Games soit un groupe de chr\u00e9tiens qui cr\u00e9ent des jeux vid\u00e9o, nous ne sommes pas ce que l&rsquo;on pourrait appeler une \u00ab soci\u00e9t\u00e9 chr\u00e9tienne de jeux vid\u00e9o \u00bb et il est important pour nous d&rsquo;\u00eatre tr\u00e8s clairs \u00e0 ce sujet afin d&rsquo;\u00e9viter les attentes erron\u00e9es. Nous cr\u00e9ons des jeux qui seront fond\u00e9s et aliment\u00e9s par la pens\u00e9e chr\u00e9tienne et la compr\u00e9hension chr\u00e9tienne de la r\u00e9alit\u00e9.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/www.globalswitchboard.io\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/switch-board-logo.jpg\" alt=\"\" class=\"wp-image-8706 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/switch-board-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/switch-board-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/switch-board-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/www.globalswitchboard.io\/\" target=\"_blank\" rel=\"noreferrer noopener\">Switchboard<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Switchboard est une plateforme en ligne qui met en relation des croyants avec des missionnaires et des organisations \u00e0 but non lucratif afin de fournir virtuellement des comp\u00e9tences pour servir le Mandat Missionnaire !<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/thechurch.digital\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/church-digital-logo.jpg\" alt=\"\" class=\"wp-image-8713 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/church-digital-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/church-digital-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/church-digital-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/thechurch.digital\" target=\"_blank\" rel=\"noreferrer noopener\">theChurch.digital<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Premi\u00e8re en son genre, theChurch.digital est une organisation d&rsquo;envoi de missions num\u00e9riques. En d\u00e9veloppant une missiologie num\u00e9rique, theChurch.digital a une vision unique du monde num\u00e9rique appel\u00e9e \u00ab\u00a0plateformes en tant que lieux\u00a0\u00bb. La fa\u00e7on dont la plupart des organisations missionnaires consid\u00e8rent des lieux comme l&rsquo;Inde, le Br\u00e9sil, etc. est la m\u00eame que celle dont nous consid\u00e9rons les plateformes num\u00e9riques comme Twitch, la r\u00e9alit\u00e9 virtuelle, Facebook, etc. En \u00e9quipant les missionnaires num\u00e9riques et en habilitant les implanteurs d&rsquo;\u00e9glises num\u00e9riques et m\u00e9taverses, l&rsquo;objectif de theChurch.digital est d&rsquo;atteindre num\u00e9riquement les personnes que les b\u00e2timents d&rsquo;\u00e9glise et le minist\u00e8re physique sont incapables d&rsquo;atteindre.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/www.unfoldingword.org\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/unfolding-world-logo.jpg\" alt=\"\" class=\"wp-image-8720 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/unfolding-world-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/unfolding-world-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/unfolding-world-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"https:\/\/www.unfoldingword.org\" target=\"_blank\" rel=\"noreferrer noopener\">unfoldingWord<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Nous travaillons avec des responsables d&rsquo;\u00c9glise du monde entier qui cherchent \u00e0 ancrer leurs \u00c9glises dans la saine doctrine, mais qui n&rsquo;ont pas acc\u00e8s \u00e0 des traductions de la Bible dans les langues parl\u00e9es par leur peuple. En dotant ces responsables de ressources bibliques et d&rsquo;une formation efficace, nous leur donnons les moyens de traduire la Bible avec excellence et efficacit\u00e9 dans toutes les langues qui en ont besoin.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/myfaithventure.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/venture-logo.jpg\" alt=\"\" class=\"wp-image-8727 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/venture-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/venture-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/venture-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/myfaithventure.com\" target=\"_blank\" rel=\"noreferrer noopener\">Venture<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Le discipulat est la premi\u00e8re lacune du Mandat Missionnaire, et il n&rsquo;y a pas assez de formateurs \u00e9quip\u00e9s dans le monde. Venture a pour mission de combler cette lacune en construisant la premi\u00e8re plateforme de formation de disciples personnalis\u00e9e au monde, aliment\u00e9e par l&rsquo;IA. Gr\u00e2ce \u00e0 un coach IA personnel, des parcours de discipulat personnalis\u00e9s et des \u00e9tapes pratiques, Venture aide les croyants \u00e0 marcher \u00e0 la mani\u00e8re de J\u00e9sus dans la vie de tous les jours. Venez essayer Venture par vous-m\u00eame !<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top org-logo\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/xriglobal.ai\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/xri-logo.jpg\" alt=\"\" class=\"wp-image-8734 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/xri-logo.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/xri-logo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/xri-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<h5 class=\"wp-block-heading has-text-align-left\"><a href=\"http:\/\/xriglobal.ai\" target=\"_blank\" rel=\"noreferrer noopener\">XRI Global<\/a><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">XRI Global est une soci\u00e9t\u00e9 de recherche et de d\u00e9ploiement dont la raison d&rsquo;\u00eatre est de permettre aux locuteurs de toutes les langues de s&rsquo;\u00e9panouir gr\u00e2ce \u00e0 la technologie linguistique. Nous tirons parti des capacit\u00e9s de l&rsquo;intelligence artificielle pour r\u00e9soudre le probl\u00e8me de la p\u00e9nurie de donn\u00e9es pour toutes les langues. Nous collectons des donn\u00e9es d&rsquo;entra\u00eenement \u00e0 l&rsquo;IA pour les langues du monde entier et construisons des syst\u00e8mes de traduction, des syst\u00e8mes vocaux et de grands mod\u00e8les linguistiques pour de multiples cas d&rsquo;utilisation en aval. D&rsquo;ici 10 \u00e0 15 ans, il n&rsquo;y aura plus de barri\u00e8re linguistique. XRI rend cela possible.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" id=\"micro-talk-sched\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-left\">Programme des micro-discussions<\/h3>\n\n\n\n<div style=\"position: relative; width: 100%; height: 0; padding-top: 56.2500%;\n padding-bottom: 0; box-shadow: 0 2px 8px 0 rgba(63,69,81,0.16); margin-top: 1.6em; margin-bottom: 0.9em; overflow: hidden;\n border-radius: 8px; will-change: transform;\">\n  <iframe loading=\"lazy\" style=\"position: absolute; width: 100%; height: 100%; top: 0; left: 0; border: none; padding: 0;margin: 0;\"\n    src=\"https:\/\/www.canva.com\/design\/DAGRWP_CdCg\/ab0yYAf9ZvqU-oyfW62XOg\/view?embed\" allowfullscreen=\"allowfullscreen\" allow=\"fullscreen\">\n  <\/iframe>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" id=\"floor-plan\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Carte de pr\u00e9sentation<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57cd41c7ff9&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57cd41c7ff9\" class=\"aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/digital-discovery-center-floor-plan-1024x576.jpg\" alt=\"\" class=\"wp-image-8447\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/digital-discovery-center-floor-plan-1024x576.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/digital-discovery-center-floor-plan-300x169.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/digital-discovery-center-floor-plan-768x432.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/digital-discovery-center-floor-plan-1536x864.jpg 1536w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/digital-discovery-center-floor-plan-1400x788.jpg 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/digital-discovery-center-floor-plan.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Faire progresser le Mandat missionnaire dans un monde connect\u00e9 Explorez le Centre de d\u00e9couverte num\u00e9rique au Quatri\u00e8me congr\u00e8s de Lausanne, o\u00f9 vous pourrez utiliser des outils num\u00e9riques, pratiques pour \u00e9laborer des strat\u00e9gies permettant de diffuser l&rsquo;Evangile \u00e0 l&rsquo;\u00e8re num\u00e9rique. Cet espace offre la possibilit\u00e9 d&rsquo;apprendre d&rsquo;organisations exp\u00e9riment\u00e9es et d&rsquo;examiner&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9546","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Centre de d\u00e9couverte num\u00e9rique - The Fourth Lausanne Congress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centre de d\u00e9couverte num\u00e9rique - The Fourth Lausanne Congress\" \/>\n<meta property=\"og:description\" content=\"Faire progresser le Mandat missionnaire dans un monde connect\u00e9 Explorez le Centre de d\u00e9couverte num\u00e9rique au Quatri\u00e8me congr\u00e8s de Lausanne, o\u00f9 vous pourrez utiliser des outils num\u00e9riques, pratiques pour \u00e9laborer des strat\u00e9gies permettant de diffuser l&rsquo;Evangile \u00e0 l&rsquo;\u00e8re num\u00e9rique. Cet espace offre la possibilit\u00e9 d&rsquo;apprendre d&rsquo;organisations exp\u00e9riment\u00e9es et d&rsquo;examiner...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/\" \/>\n<meta property=\"og:site_name\" content=\"The Fourth Lausanne Congress\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-21T01:30:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/ddc-landing-4.gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/\",\"name\":\"Centre de d\u00e9couverte num\u00e9rique - The Fourth Lausanne Congress\",\"isPartOf\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/ddc-landing-4.gif\",\"datePublished\":\"2024-09-12T01:50:27+00:00\",\"dateModified\":\"2024-09-21T01:30:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/#primaryimage\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/ddc-landing-4.gif\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/ddc-landing-4.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/congress.lausanne.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centre de d\u00e9couverte num\u00e9rique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"name\":\"The Fourth Lausanne Congress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\",\"name\":\"The Fourth Lausanne Congress\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"width\":1477,\"height\":266,\"caption\":\"The Fourth Lausanne Congress\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centre de d\u00e9couverte num\u00e9rique - The Fourth Lausanne Congress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/","og_locale":"fr_FR","og_type":"article","og_title":"Centre de d\u00e9couverte num\u00e9rique - The Fourth Lausanne Congress","og_description":"Faire progresser le Mandat missionnaire dans un monde connect\u00e9 Explorez le Centre de d\u00e9couverte num\u00e9rique au Quatri\u00e8me congr\u00e8s de Lausanne, o\u00f9 vous pourrez utiliser des outils num\u00e9riques, pratiques pour \u00e9laborer des strat\u00e9gies permettant de diffuser l&rsquo;Evangile \u00e0 l&rsquo;\u00e8re num\u00e9rique. Cet espace offre la possibilit\u00e9 d&rsquo;apprendre d&rsquo;organisations exp\u00e9riment\u00e9es et d&rsquo;examiner...","og_url":"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/","og_site_name":"The Fourth Lausanne Congress","article_modified_time":"2024-09-21T01:30:14+00:00","og_image":[{"url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/ddc-landing-4.gif","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"23 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/","url":"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/","name":"Centre de d\u00e9couverte num\u00e9rique - The Fourth Lausanne Congress","isPartOf":{"@id":"https:\/\/congress.lausanne.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/#primaryimage"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/#primaryimage"},"thumbnailUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/ddc-landing-4.gif","datePublished":"2024-09-12T01:50:27+00:00","dateModified":"2024-09-21T01:30:14+00:00","breadcrumb":{"@id":"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/#primaryimage","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/ddc-landing-4.gif","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/ddc-landing-4.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/congress.lausanne.org\/fr\/centre-de-decouverte-numerique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/congress.lausanne.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Centre de d\u00e9couverte num\u00e9rique"}]},{"@type":"WebSite","@id":"https:\/\/congress.lausanne.org\/fr\/#website","url":"https:\/\/congress.lausanne.org\/fr\/","name":"The Fourth Lausanne Congress","description":"","publisher":{"@id":"https:\/\/congress.lausanne.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/congress.lausanne.org\/fr\/#organization","name":"The Fourth Lausanne Congress","url":"https:\/\/congress.lausanne.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","width":1477,"height":266,"caption":"The Fourth Lausanne Congress"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/comments?post=9546"}],"version-history":[{"count":0,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9546\/revisions"}],"wp:attachment":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/media?parent=9546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":9563,"date":"2024-09-09T02:01:27","date_gmt":"2024-09-09T02:01:27","guid":{"rendered":"https:\/\/congress.lausanne.org\/?page_id=9563"},"modified":"2024-09-16T01:08:24","modified_gmt":"2024-09-16T01:08:24","slug":"les-intervenants-du-congres","status":"publish","type":"page","link":"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/","title":{"rendered":"Les intervenants du congr\u00e8s"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Responsables des \u00e9tudes bibliques<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-addb6697cccf640bb3104b82747ec1f5 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye.jpg\" alt=\"\" class=\"wp-image-7884\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong>Femi Adeleye<\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Ghana<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le R\u00e9v\u00e9rend docteur Femi Adeleye, directeur de Christian Impact et directeur pour l\u2019Afrique de Langham Preaching, est un auteur prolifique et un universitaire.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Patrick-Fung-1024x1024.jpg\" alt=\"\" class=\"wp-image-7891\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Patrick-Fung-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Patrick-Fung-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Patrick-Fung-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Patrick-Fung-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Patrick-Fung.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong>Patrick Fung<\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Singapour<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le R\u00e9v\u00e9rend Dr Patrick Fung est m\u00e9decin, pasteur ordonn\u00e9 et missionnaire&nbsp;; il est titulaire d\u2019un doctorat en histoire de l\u2019\u00c9glise chinoise. Il est actuellement ambassadeur mondial de OMF International et pr\u00e9sident du programme du Quatri\u00e8me congr\u00e8s de Lausanne.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Julia-Garschagen-1024x1024.jpg\" alt=\"\" class=\"wp-image-7898\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Julia-Garschagen-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Julia-Garschagen-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Julia-Garschagen-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Julia-Garschagen-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Julia-Garschagen.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong>Julia Garschagen<\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Allemagne<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Julia Garschagen, directrice de l\u2019Institut Pontes pour la science, la culture et la foi, enseigne l\u2019apolog\u00e9tique dans un centre de formation th\u00e9ologique et codirige la plus grande action d\u2019\u00e9vang\u00e9lisation de la jeunesse entreprise par le monde \u00e9vang\u00e9lique germanophone.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ronaldo-Lidorio-1024x1024.jpg\" alt=\"\" class=\"wp-image-7905\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ronaldo-Lidorio-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ronaldo-Lidorio-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ronaldo-Lidorio-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ronaldo-Lidorio-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ronaldo-Lidorio.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong>Ronaldo Lid\u00f3rio<\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Br\u00e9sil<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ronaldo Lid\u00f3rio est pasteur presbyt\u00e9rien br\u00e9silien et travaille actuellement \u00e0 l\u2019\u00e9vang\u00e9lisation et au d\u00e9veloppement du leadership dans la r\u00e9gion amazonienne.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-eadad57aea9b40e336337bc8ef0bd656 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Philip-Ryken.jpg\" alt=\"\" class=\"wp-image-7912\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Philip-Ryken.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Philip-Ryken-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Philip-Ryken-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Philip-Ryken-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Philip-Ryken-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong>Philip Ryken<\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9tats-Unis<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Philip Ryken est le huiti\u00e8me pr\u00e9sident du Wheaton College et l\u2019auteur de plus de 50 livres et commentaires bibliques. Il vit et travaille aux \u00c9tats-Unis.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Anne-Zaki-1024x1024.jpg\" alt=\"\" class=\"wp-image-7919\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Anne-Zaki-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Anne-Zaki-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Anne-Zaki-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Anne-Zaki-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Anne-Zaki.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong>Anne Zaki<\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9gypte<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La docteure Anne E. Zaki est professeure de pr\u00e9dication et de th\u00e9ologie pratique au Evangelical Theological Seminary du Caire. Son expertise en th\u00e9ologie et psychologie lui permet d\u2019apporter un \u00e9clairage singulier au Quatri\u00e8me congr\u00e8s de Lausanne.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Intervenants des pl\u00e9ni\u00e8res du matin<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-13994abfff5413da6260cabb1e8a60a2 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sara-Akhavan.jpg\" alt=\"\" class=\"wp-image-8005\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sara-Akhavan.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sara-Akhavan-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sara-Akhavan-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sara-Akhavan-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sara-Akhavan-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong>Sara Akhavan<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Iran&nbsp;\/ Argentine<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir \u00e9t\u00e9 emprisonn\u00e9e pour ses activit\u00e9s d\u2019\u00e9vang\u00e9lisation dans son pays natal, l\u2019Iran, Sara Akhavan a pass\u00e9 la derni\u00e8re d\u00e9cennie \u00e0 implanter des \u00c9glises et \u00e0 former des responsables d\u2019\u00c9glises en Turquie. Elle vit aujourd\u2019hui en Argentine avec son mari Samuel.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Arslan-Arif-1080x1080-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-8411\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Arslan-Arif-1080x1080-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Arslan-Arif-1080x1080-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Arslan-Arif-1080x1080-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Arslan-Arif-1080x1080-1-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Arslan-Arif-1080x1080-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong>Arslan Arif<\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Pakistan<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arslan Arif est au service du d\u00e9partement des prisons au Pakistan. Il aide \u00e0 transformer la vie des prisonniers par la Parole de Dieu. Il distribue \u00e9galement des bibles audio aux chr\u00e9tiens analphab\u00e8tes.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Nana-Yaw-Offei-Awuku-1024x1024.jpg\" alt=\"\" class=\"wp-image-8012\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Nana-Yaw-Offei-Awuku-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Nana-Yaw-Offei-Awuku-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Nana-Yaw-Offei-Awuku-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Nana-Yaw-Offei-Awuku-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Nana-Yaw-Offei-Awuku.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong>Nana Yaw Offei Awuku<\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Ghana<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nana Yaw Offei Awuku a \u00e9t\u00e9 le directeur pionnier de G\u00e9n\u00e9ration des Jeunes Leaders du Mouvement de Lausanne et une figure cl\u00e9 de son lancement en 2016. Il vit et travaille au Ghana.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sarah-Breuel-1024x1024.jpg\" alt=\"\" class=\"wp-image-8020\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sarah-Breuel-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sarah-Breuel-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sarah-Breuel-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sarah-Breuel-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sarah-Breuel.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong>Sarah Breuel<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Italie&nbsp;\/ Br\u00e9sil<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Figurant sur la liste des 33 leaders de moins de 33 ans de <em>Christianity Today<\/em>, Sarah Breuel s\u2019est distingu\u00e9e par sa fa\u00e7on transformatrice de diriger. Fondatrice et directrice ex\u00e9cutive de Revive Europe et ayant implant\u00e9 une \u00c9glise \u00e0 Rome, Sarah est profond\u00e9ment engag\u00e9e en faveur du r\u00e9veil et de l\u2019\u00e9vang\u00e9lisation.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Eun-Ah-Cho-1024x1024.jpg\" alt=\"\" class=\"wp-image-8027\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Eun-Ah-Cho-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Eun-Ah-Cho-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Eun-Ah-Cho-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Eun-Ah-Cho-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Eun-Ah-Cho.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong>Eun Ah Cho<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9tats-Unis&nbsp;\/ Cor\u00e9e du Sud<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Dr Eun Ah Cho est professeur associ\u00e9 au Gordon Conwell-Theological Seminary et doyen du Gordon-Conwell Institute.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-12dc879abf38c7bebd21f5b1bc1ff1a4 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Khara-Collymore-Lashley-1080x1080-1.jpg\" alt=\"\" class=\"wp-image-8418\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Khara-Collymore-Lashley-1080x1080-1.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Khara-Collymore-Lashley-1080x1080-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Khara-Collymore-Lashley-1080x1080-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Khara-Collymore-Lashley-1080x1080-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Khara-Collymore-Lashley-1080x1080-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong>Khara Collymore-Lashley<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>La Barbade<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Khara Collymore-Lashley est une m\u00e9decin praticienne de la Barbade passionn\u00e9e par la m\u00e9decine et la mission mondiale. Elle est actuellement la repr\u00e9sentante de YLGen au Conseil de Lausanne.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-161af26ec3e8d212ef8144c21664073d is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Samuel-Cooper.jpg\" alt=\"\" class=\"wp-image-8034\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Samuel-Cooper.jpg 540w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Samuel-Cooper-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Samuel-Cooper-150x150.jpg 150w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong>Sam Couper<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Royaume-Uni<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coordinateur de terrain pour Revive Europe, Sam Couper a consacr\u00e9 sa carri\u00e8re et sa vie \u00e0 \u00e9vang\u00e9liser les non-atteints en Europe.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bob-Doll-1024x1024.jpg\" alt=\"\" class=\"wp-image-8041\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bob-Doll-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bob-Doll-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bob-Doll-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bob-Doll-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bob-Doll.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong>Bob Doll<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9tats-Unis<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec plus de 40 ans d\u2019exp\u00e9rience dans le domaine de l\u2019investissement, Bob Doll est actuellement DG et directeur des investissements de Crossmark Global Investments.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon-1024x1024.jpg\" alt=\"\" class=\"wp-image-8048\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong>Delphine Fanfon<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Cameroun<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Delphine Fanfon vit au Cameroun o\u00f9 elle est DG de Me4Real International et directrice r\u00e9gionale de LeadersSource en Afrique et en Asie. Son doctorat en leadership strat\u00e9gique et sa carri\u00e8re refl\u00e8tent l\u2019engagement de longue date de Delphine en faveur du d\u00e9veloppement et de la transformation de la fonction dirigeante.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Farshid-Fati-1024x1024.jpg\" alt=\"\" class=\"wp-image-8055\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Farshid-Fati-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Farshid-Fati-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Farshid-Fati-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Farshid-Fati-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Farshid-Fati.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong>Farshid Fathi<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Iran<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Farshid Fathi, qui travaille avec Elam Ministries, a consacr\u00e9 sa vie \u00e0 soutenir l\u2019\u00c9glise en Iran et dans le monde persanophone.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-d001838ba3731ea43ad2af6fc3680ef1 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Kwabena-Asamoah-Gyadu.jpg\" alt=\"\" class=\"wp-image-8062\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Kwabena-Asamoah-Gyadu.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Kwabena-Asamoah-Gyadu-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Kwabena-Asamoah-Gyadu-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Kwabena-Asamoah-Gyadu-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Kwabena-Asamoah-Gyadu-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong>Kwabena Asamoah Gyadu<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Ghana<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le r\u00e9v\u00e9rend professeur Kwabena Asamoah est pasteur ordonn\u00e9 de l\u2019\u00c9glise m\u00e9thodiste du Ghana et professeur au Trinity Theological Seminary au Ghana.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sona-Kazaniian-1024x1024.jpg\" alt=\"\" class=\"wp-image-8069\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sona-Kazaniian-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sona-Kazaniian-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sona-Kazaniian-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sona-Kazaniian-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Sona-Kazaniian.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong>Sona Kazanjian<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9mirats arabes unis&nbsp;\/ Arm\u00e9nie<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sona Kazanjian est au service de l\u2019\u00c9glise locale de Duba\u00ef depuis 2000 et s\u2019efforce d\u2019introduire Movement Day \u00e0 Duba\u00ef et au Moyen-Orient.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michel-Kenmogne-1024x1024.jpg\" alt=\"\" class=\"wp-image-8076\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michel-Kenmogne-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michel-Kenmogne-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michel-Kenmogne-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michel-Kenmogne-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michel-Kenmogne.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Michel Kenmogne<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Cameroun&nbsp;\/ Allemagne<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Dr Michel Kenmogne est actuellement directeur g\u00e9n\u00e9ral de SIL International et titulaire d\u2019un doctorat en linguistique africaine de l\u2019universit\u00e9 de Buea. Il vit avec sa famille en Allemagne.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ravil-Mashanlo-1024x1024.jpg\" alt=\"\" class=\"wp-image-8083\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ravil-Mashanlo-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ravil-Mashanlo-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ravil-Mashanlo-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ravil-Mashanlo-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ravil-Mashanlo.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong>Ravil Mashanlo<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Kyrgyzstan<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Directeur du d\u00e9veloppement pour l\u2019Asie centrale chez Luke Services International, Ravil Mashanlo se passionne pour une \u00c9glise mondiale qui accueille tous les milieux et toutes les cultures pour l\u2019amour de l\u2019\u00c9vangile.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-f15699e3b26be245797438e46fc0b1bd is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Allan-Matamoros.jpg\" alt=\"\" class=\"wp-image-8090\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Allan-Matamoros.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Allan-Matamoros-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Allan-Matamoros-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Allan-Matamoros-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Allan-Matamoros-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong>Allan Matamoros<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Costa Rica&nbsp;\/ Espagne<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Directeur de terrain de COMIBAM et pr\u00e9sident de Vision 5:9, Allan Matamoros est au service des non-atteints en Am\u00e9rique latine et dans le monde musulman.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jocabed-Solano-Miselis-1024x1024.jpg\" alt=\"\" class=\"wp-image-8097\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jocabed-Solano-Miselis-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jocabed-Solano-Miselis-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jocabed-Solano-Miselis-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jocabed-Solano-Miselis-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jocabed-Solano-Miselis.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong>Jocabed Solano Miselis<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Panama<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jocabed Solano Miselis, doctorante au NAIITS et directrice d\u2019Indigenous Memory, est profond\u00e9ment passionn\u00e9e par la justice environnementale et le r\u00f4le des peuples autochtones dans le Mandat missionnaire.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Joanna-Ng-1080x1080-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-8425\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Joanna-Ng-1080x1080-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Joanna-Ng-1080x1080-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Joanna-Ng-1080x1080-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Joanna-Ng-1080x1080-1-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Joanna-Ng-1080x1080-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong>Joanna Ng<\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Canada<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joanna Ng est un ma\u00eetre inventeur avec plus de 20 articles acad\u00e9miques et 49 brevets \u00e0 son nom. Ses travaux avec IBM Canada et Devarim Design ont permis de repousser les limites de la cognition augment\u00e9e et de l&rsquo;intelligence artificielle.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ole-Magnus-Olafsrud-1024x1024.jpg\" alt=\"\" class=\"wp-image-8104\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ole-Magnus-Olafsrud-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ole-Magnus-Olafsrud-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ole-Magnus-Olafsrud-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ole-Magnus-Olafsrud-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ole-Magnus-Olafsrud.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Ole-Magnus Olafsrud<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Norv\u00e8ge<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ole-Magnus Olasfrud occupe diverses fonctions au sein du Mouvement de Lausanne et il est le directeur g\u00e9n\u00e9ral de Barnabas Focus. Il vit en Norv\u00e8ge avec ses trois fils et ses 13 petits-enfants.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Mac-Pier-1024x1024.jpg\" alt=\"\" class=\"wp-image-8111\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Mac-Pier-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Mac-Pier-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Mac-Pier-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Mac-Pier-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Mac-Pier.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong>Mac Pier<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9tats-Unis<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Dr Mac Pier a fond\u00e9 Church Multiplication Alliance et l\u2019organisation Movement Day avec Tim Keller, et il est l\u2019auteur de dix livres.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-a15971df8066bfa900dc01c606367e8c is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Dale-Stephenson.jpg\" alt=\"\" class=\"wp-image-8118\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Dale-Stephenson.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Dale-Stephenson-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Dale-Stephenson-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Dale-Stephenson-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Dale-Stephenson-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Dale Stephenson<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Australie<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pasteur de l\u2019\u00c9glise baptiste Crossway, Dale Stephenson se pr\u00e9occupe beaucoup de l\u2019\u00e9vang\u00e9lisation et de la prise en charge des Australiens s\u00e9culiers et non atteints.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bishop-Efraim-Tendero-1024x1024.jpg\" alt=\"\" class=\"wp-image-8160\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bishop-Efraim-Tendero-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bishop-Efraim-Tendero-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bishop-Efraim-Tendero-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bishop-Efraim-Tendero-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Bishop-Efraim-Tendero.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong>Efraim Tendero<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Philippines<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9v\u00eaque Efraim M Tendero est Directeur ex\u00e9cutif du Galilean Movement et ambassadeur mondial de l\u2019Alliance \u00e9vang\u00e9lique mondiale. Il vit dans son pays natal, les Philippines.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Denise-Margaret-Thompson-1024x1024.jpg\" alt=\"\" class=\"wp-image-8132\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Denise-Margaret-Thompson-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Denise-Margaret-Thompson-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Denise-Margaret-Thompson-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Denise-Margaret-Thompson-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Denise-Margaret-Thompson.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Denise-Margaret Thompson<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Trinit\u00e9-et-Tobago&nbsp;\/ \u00c9tats-Unis<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019engagement de Denise dans le service chr\u00e9tien en milieu universitaire comporte de multiples facettes. Elle cherche \u00e0 transformer le monde universitaire en communaut\u00e9s de disciples qui t\u00e9moignent, gr\u00e2ce \u00e0 ses r\u00f4les au sein d\u2019InterVarsity USA et de Caribbean Fellowship of Evangelical Students. Parall\u00e8lement \u00e0 sa fonction de directrice associ\u00e9e nationale d\u2019InterVarsity USA, Denise est au service de l\u2019universit\u00e9 de Stanford en tant qu\u2019aum\u00f4ni\u00e8re de IVGrad et du campus de la facult\u00e9. Elle est \u00e9galement coordinatrice du service chr\u00e9tien aupr\u00e8s des dipl\u00f4m\u00e9s et professeurs pour le Caribbean Fellowship of Evangelical Students. Denise collabore depuis longtemps avec le Mouvement de Lausanne, puisqu\u2019elle est l\u2019une des trois co-catalyseurs nomm\u00e9s pour le r\u00e9seau AMEN propos\u00e9 parle Mouvement de Lausanne.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Babu-Verghese.jpg\" alt=\"\" class=\"wp-image-8139\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Babu-Verghese.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Babu-Verghese-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Babu-Verghese-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Babu-Verghese-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Babu-Verghese-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Babu Verghese<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Inde<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Babu Verghese est journaliste, historien, linguiste et auteur de 27 livres. Il vit et travaille en Inde.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Merari-Pena-Vidal-1080x1080-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-8432\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Merari-Pena-Vidal-1080x1080-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Merari-Pena-Vidal-1080x1080-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Merari-Pena-Vidal-1080x1080-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Merari-Pena-Vidal-1080x1080-1-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Merari-Pena-Vidal-1080x1080-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong>Merari Pe\u00f1a Vidal<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Porto Rico<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merari Pe\u00f1a Vidal est une entrepreneuse de Porto Rico qui poss\u00e8de une entreprise prosp\u00e8re de bijoux de mode. Elle dirige Oasis Empresarial, une organisation \u00e0 but non lucratif qui aide les femmes d&rsquo;affaires \u00e0 s&rsquo;\u00e9manciper en appliquant les principes bibliques. Avec son mari, elle est en train d&rsquo;implanter une \u00c9glise destin\u00e9e \u00e0 atteindre les non-chr\u00e9tiens.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-4d874e58cd0cf6a9ae2c0d702a09308f is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rick-Warren-1024x1024.jpg\" alt=\"\" class=\"wp-image-8146\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rick-Warren-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rick-Warren-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rick-Warren-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rick-Warren-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rick-Warren.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Rick Warren<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9tats-Unis<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9sign\u00e9 par <em>Time Magazine<\/em> comme le leader spirituel le plus influent d\u2019Am\u00e9rique et l\u2019une des 100 personnes les plus influentes du monde, Rick Warren est le fondateur de l\u2019\u00e9glise Saddleback et de nombreuses autres entit\u00e9s d\u00e9di\u00e9es au Mandat missionnaire.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Billy-Wilson-1024x1024.jpg\" alt=\"\" class=\"wp-image-8153\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Billy-Wilson-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Billy-Wilson-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Billy-Wilson-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Billy-Wilson-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Billy-Wilson.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Billy Wilson<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9tats-Unis<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Dr Billy Wilson, titulaire d\u2019un doctorat en th\u00e9ologie du Pentecostal Theological Seminary, est le quatri\u00e8me pr\u00e9sident de l\u2019universit\u00e9 Oral Roberts et l\u2019un des principaux dirigeants du mouvement pentec\u00f4tiste. Il est \u00e9galement membre d\u2019Empowered21.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-hwa-yung-1024x1024.jpg\" alt=\"\" class=\"wp-image-8245\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-hwa-yung-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-hwa-yung-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-hwa-yung-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-hwa-yung-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-hwa-yung.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Hwa Yung<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Malaisie<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que ce soit dans son r\u00f4le d\u2019enseignant dans des centres de formation th\u00e9ologiques en Asie du Sud-Est ou celui de pasteur, l\u2019\u00e9v\u00eaque \u00e9m\u00e9rite Hwa Yung de l\u2019\u00c9glise m\u00e9thodiste de Malaisie a tout au long de sa vie fait preuve d\u2019un engagement in\u00e9branlable en faveur de l\u2019\u00e9vang\u00e9lisation.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Intervenants des pl\u00e9ni\u00e8res du soir<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-5b31b6bcaeddcb2c281ee087a35889b5 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ruth-Padilla-DeBorst.jpg\" alt=\"\" class=\"wp-image-8167\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ruth-Padilla-DeBorst.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ruth-Padilla-DeBorst-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ruth-Padilla-DeBorst-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ruth-Padilla-DeBorst-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ruth-Padilla-DeBorst-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Ruth Padilla DeBorst<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Costa Rica&nbsp;\/ Argentine<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Professeure associ\u00e9e au Western Theological Seminary, Ruth Padilla DeBorst a pass\u00e9 sa vie au service du Costa Rica et de l\u2019Am\u00e9rique latine en g\u00e9n\u00e9ral.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Katherine-Hayhoe-1024x1024.jpg\" alt=\"\" class=\"wp-image-8174\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Katherine-Hayhoe-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Katherine-Hayhoe-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Katherine-Hayhoe-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Katherine-Hayhoe-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Katherine-Hayhoe.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Katharine Hayhoe<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Canada<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Katherine Hayhoe, scientifique en chef de Nature Conservancy et professeure \u00e0 l\u2019universit\u00e9 Texas Tech, a consacr\u00e9 sa vie \u00e0 la lutte contre le changement climatique. Son approche synth\u00e9tise \u00e0 la fois sa vaste exp\u00e9rience de scientifique et sa foi personnelle.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-698ae30738b385f2d8f1f2e5031d974e is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Byung-Yeon-Kim-1080x1080-1.jpg\" alt=\"\" class=\"wp-image-8403\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Byung-Yeon-Kim-1080x1080-1.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Byung-Yeon-Kim-1080x1080-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Byung-Yeon-Kim-1080x1080-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Byung-Yeon-Kim-1080x1080-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Byung-Yeon-Kim-1080x1080-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Byung-Yeon Kim<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Cor\u00e9e du Sud<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Byung-Yeon Kim est un \u00e9minent professeur d&rsquo;\u00e9conomie \u00e0 l&rsquo;universit\u00e9 nationale de S\u00e9oul en Cor\u00e9e du Sud, sp\u00e9cialiste de l&rsquo;\u00e9conomie nord-cor\u00e9enne. Il a re\u00e7u de nombreux prix pour ses recherches.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jaehoon-Lee-1080x1080-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-8375\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jaehoon-Lee-1080x1080-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jaehoon-Lee-1080x1080-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jaehoon-Lee-1080x1080-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jaehoon-Lee-1080x1080-1-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jaehoon-Lee-1080x1080-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Jaehoon Lee<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Cor\u00e9e du Sud<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jaehoo Lee est le pasteur principal de l&rsquo;\u00c9glise communautaire d&rsquo;Onnuri en Cor\u00e9e du Sud, le pr\u00e9sident de Lausanne Cor\u00e9e et le copr\u00e9sident du comit\u00e9 d&rsquo;organisation du quatri\u00e8me congr\u00e8s de Lausanne.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rula-Khoury-Mansour-1080x1080-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-8382\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rula-Khoury-Mansour-1080x1080-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rula-Khoury-Mansour-1080x1080-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rula-Khoury-Mansour-1080x1080-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rula-Khoury-Mansour-1080x1080-1-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Rula-Khoury-Mansour-1080x1080-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Rula Khoury Mansour<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Isra\u00ebl<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rula Khoury Mansour, avocate et th\u00e9ologienne chr\u00e9tienne, est la fondatrice et directrice du Centre de Nazareth pour les \u00c9tudes sur la Paix. Elle a consacr\u00e9 sa carri\u00e8re \u00e0 la construction de la paix dans le monde.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-54b050d51944057e7c7896259ae860e1 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Emmanuel-Ndikumana-1080x1080-1.jpg\" alt=\"\" class=\"wp-image-8389\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Emmanuel-Ndikumana-1080x1080-1.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Emmanuel-Ndikumana-1080x1080-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Emmanuel-Ndikumana-1080x1080-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Emmanuel-Ndikumana-1080x1080-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Emmanuel-Ndikumana-1080x1080-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Emmanuel Ndikumana<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Burundi<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Emmanuel Ndikumana est actuellement directeur r\u00e9gional du Mouvement de Lausanne pour l\u2019Afrique francophone et fondateur de Partners Trust International, aujourd\u2019hui PTI Church, qui cherche \u00e0 promouvoir un leadership transformationnel au Burundi.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michael-Oh.jpg\" alt=\"\" class=\"wp-image-8439\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michael-Oh.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michael-Oh-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michael-Oh-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michael-Oh-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Michael-Oh-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Michael Oh<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9tats-Unis | Japon<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Dr Michael Young-Sukh Oh est le PDG et le directeur ex\u00e9cutif mondial du Mouvement de Lausanne.\u00a0<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Gideon-Para-Mallam-1024x1024.jpg\" alt=\"\" class=\"wp-image-8181\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Gideon-Para-Mallam-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Gideon-Para-Mallam-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Gideon-Para-Mallam-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Gideon-Para-Mallam-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Gideon-Para-Mallam.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Gideon Para-Mallam<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Nigeria<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis plus de 30 ans, Gideon Para-Mallam travaille pour l\u2019International Fellowship of Evangelical Students (IFES-GBU).<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Vaughn-Roberts-1024x1024.jpg\" alt=\"\" class=\"wp-image-8188\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Vaughn-Roberts-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Vaughn-Roberts-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Vaughn-Roberts-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Vaughn-Roberts-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Vaughn-Roberts.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Vaughan Roberts<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Royaume-Uni<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vaughan Roberts est l\u2019actuel pasteur de l\u2019\u00c9glise St Ebbe \u00e0 Oxford, o\u00f9 il travaille depuis 1991. Il a suivi une formation de pasteur anglican \u00e0 Wycliffe Hall, Oxford, et a \u00e9crit un certain nombre d\u2019ouvrages th\u00e9ologiques.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-d5ae97cc7c0ed895f9755dcacf89d27e is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ivan-Rusyn-1080x1080-1.jpg\" alt=\"\" class=\"wp-image-8396\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ivan-Rusyn-1080x1080-1.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ivan-Rusyn-1080x1080-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ivan-Rusyn-1080x1080-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ivan-Rusyn-1080x1080-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Ivan-Rusyn-1080x1080-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Ivan Rusyn<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Ukraine<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ivan Rusyn est pr\u00e9sident et professeur de missions au S\u00e9minaire Th\u00e9ologique \u00c9vang\u00e9lique Ukrainien (UETS) et ministre ordonn\u00e9 de l&rsquo;\u00c9glise \u00c9vang\u00e9lique Ukrainienne. Il s&rsquo;est impliqu\u00e9 activement dans les op\u00e9rations de secours depuis le d\u00e9but de la guerre en Ukraine.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-a2b08f2ad8fd5b39031fb9138f496b5e is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Daniel-Kyungu-Tchikala.jpg\" alt=\"\" class=\"wp-image-8195\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Daniel-Kyungu-Tchikala.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Daniel-Kyungu-Tchikala-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Daniel-Kyungu-Tchikala-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Daniel-Kyungu-Tchikala-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Daniel-Kyungu-Tchikala-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Daniel Kyungu Tchikala<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>R\u00e9publique d\u00e9mocratique du Congo (RDC)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9v\u00eaque de la First Community of the Church of Chris, le Dr Daniel Kyungu Tchikala met son exp\u00e9rience universitaire et sa passion pour le Christ au service de la R\u00e9publique d\u00e9mocratique du Congo.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Artistes<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-b8ed4895d83aac0651897a3270755209 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Isiah6tyOne.jpg\" alt=\"\" class=\"wp-image-8202\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Isiah6tyOne.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Isiah6tyOne-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Isiah6tyOne-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Isiah6tyOne-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Isiah6tyOne-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Korean Worship team supported by Isaiah 6tyOne<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Cor\u00e9e du Sud<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isaiah 6tyOne est une communaut\u00e9 de louange missionnelle bas\u00e9e en Cor\u00e9e du Sud, dont l\u2019objectif est de renouveler et restaurer le c\u0153ur des adorateurs gr\u00e2ce \u00e0 sa musique.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Stefan-Kunz-1024x1024.jpg\" alt=\"\" class=\"wp-image-8209\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Stefan-Kunz-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Stefan-Kunz-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Stefan-Kunz-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Stefan-Kunz-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Stefan-Kunz.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Stefan Kunz<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Suisse<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stefan Kunz, artiste professionnel bas\u00e9 en Suisse, a re\u00e7u des commandes de Porsche, Nespresso et Coca-Cola. Son exp\u00e9rience professionnelle est compl\u00e9t\u00e9e par son travail avec Arthelps, o\u00f9 il partage sa sagesse cr\u00e9ative avec des milliers d\u2019\u00e9tudiants pour cr\u00e9er des fresques murales, de l\u2019Irak au Br\u00e9sil et El Savador.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Keith-Kristyn-Getty-1080x1080-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-8368\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Keith-Kristyn-Getty-1080x1080-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Keith-Kristyn-Getty-1080x1080-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Keith-Kristyn-Getty-1080x1080-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Keith-Kristyn-Getty-1080x1080-1-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Keith-Kristyn-Getty-1080x1080-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>The Getty Band<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9tats-Unis | Irlande du Nord<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Keith et Christine Getty sont des artistes d&rsquo;Irlande du Nord nomm\u00e9s aux Grammy Awards. Leurs hymnes, tels que <em>In Christ Alone<\/em>, sont chant\u00e9s par des millions de personnes dans le monde entier.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>MC<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#e6eaec\">\n<div class=\"wp-block-column is-vertically-aligned-stretch wp-elements-2b3ecb218b7b4b465a33e63598822719 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Richard-Coleman.jpg\" alt=\"\" class=\"wp-image-8216\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Richard-Coleman.jpg 1080w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Richard-Coleman-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Richard-Coleman-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Richard-Coleman-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Richard-Coleman-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Richard Coleman<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00c9thiopie&nbsp;\/ \u00c9tats-Unis<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Richard Coleman travaille actuellement pour EvaSUE et TMS Global \u00e0 Addis-Abeba, en \u00c9thiopie. L\u2019exp\u00e9rience diversifi\u00e9e de Richard dans le domaine de la pastorale interculturelle et de la pastorale \u00e9tudiante le place dans une position id\u00e9ale pour animer le Quatri\u00e8me congr\u00e8s de Lausanne, en offrant \u00e0 la fois une expertise et une vision avant-gardiste.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon-1024x1024.jpg\" alt=\"\" class=\"wp-image-8048\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Delphine-Fanfon.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Delphine Fanfon<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Cameroun<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Delphine Fanfon vit au Cameroun o\u00f9 elle est DG de Me4Real International et directrice r\u00e9gionale de LeadersSource en Afrique et en Asie. Son doctorat en leadership strat\u00e9gique et sa carri\u00e8re refl\u00e8tent l\u2019engagement de longue date de Delphine en faveur du d\u00e9veloppement et de la transformation de la fonction dirigeante.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-33ccc8b1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Simon-Seow-1024x1024.jpg\" alt=\"\" class=\"wp-image-8223\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Simon-Seow-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Simon-Seow-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Simon-Seow-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Simon-Seow-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Simon-Seow.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Simon Seow<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Singapour<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Principal strat\u00e8ge num\u00e9rique pour CRU et cofondateur d\u2019Indigitous, Simon Seow est un communicateur expert, motiv\u00e9 par sa mission de transmettre l\u2019\u00c9vangile dans l\u2019\u00e8re num\u00e9rique complexe d\u2019aujourd\u2019hui.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jeri-Jones-Sparks-1024x1024.jpg\" alt=\"\" class=\"wp-image-8230\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jeri-Jones-Sparks-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jeri-Jones-Sparks-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jeri-Jones-Sparks-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jeri-Jones-Sparks-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Jeri-Jones-Sparks.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Jeri Jones Sparks<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong> <\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong>Australie&nbsp;\/ Inde<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jeri Jones Sparks est le responsable de l\u2019action sociale \u00e0 l\u2019\u00c9glise anglicane St James de Sydney, en Australie, et directrice de la s\u00e9rie Good News. Gr\u00e2ce \u00e0 la s\u00e9rie Good News et au r\u00e9seau SATYA, elle aide les \u00c9glises locales \u00e0 atteindre les personnes originaires d\u2019Asie du Sud et du monde hindou.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Responsables des \u00e9tudes bibliques Femi Adeleye Ghana Le R\u00e9v\u00e9rend docteur Femi Adeleye, directeur de Christian Impact et directeur pour l\u2019Afrique de Langham Preaching, est un auteur prolifique et un universitaire.&nbsp; Patrick Fung Singapour Le R\u00e9v\u00e9rend Dr Patrick Fung est m\u00e9decin, pasteur ordonn\u00e9 et missionnaire&nbsp;; il est titulaire d\u2019un doctorat&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9563","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les intervenants du congr\u00e8s - The Fourth Lausanne Congress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les intervenants du congr\u00e8s - The Fourth Lausanne Congress\" \/>\n<meta property=\"og:description\" content=\"Responsables des \u00e9tudes bibliques Femi Adeleye Ghana Le R\u00e9v\u00e9rend docteur Femi Adeleye, directeur de Christian Impact et directeur pour l\u2019Afrique de Langham Preaching, est un auteur prolifique et un universitaire.&nbsp; Patrick Fung Singapour Le R\u00e9v\u00e9rend Dr Patrick Fung est m\u00e9decin, pasteur ordonn\u00e9 et missionnaire&nbsp;; il est titulaire d\u2019un doctorat...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/\" \/>\n<meta property=\"og:site_name\" content=\"The Fourth Lausanne Congress\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T01:08:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/\",\"name\":\"Les intervenants du congr\u00e8s - The Fourth Lausanne Congress\",\"isPartOf\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye.jpg\",\"datePublished\":\"2024-09-09T02:01:27+00:00\",\"dateModified\":\"2024-09-16T01:08:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/#primaryimage\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye.jpg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/congress.lausanne.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les intervenants du congr\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"name\":\"The Fourth Lausanne Congress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\",\"name\":\"The Fourth Lausanne Congress\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"width\":1477,\"height\":266,\"caption\":\"The Fourth Lausanne Congress\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les intervenants du congr\u00e8s - The Fourth Lausanne Congress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/","og_locale":"fr_FR","og_type":"article","og_title":"Les intervenants du congr\u00e8s - The Fourth Lausanne Congress","og_description":"Responsables des \u00e9tudes bibliques Femi Adeleye Ghana Le R\u00e9v\u00e9rend docteur Femi Adeleye, directeur de Christian Impact et directeur pour l\u2019Afrique de Langham Preaching, est un auteur prolifique et un universitaire.&nbsp; Patrick Fung Singapour Le R\u00e9v\u00e9rend Dr Patrick Fung est m\u00e9decin, pasteur ordonn\u00e9 et missionnaire&nbsp;; il est titulaire d\u2019un doctorat...","og_url":"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/","og_site_name":"The Fourth Lausanne Congress","article_modified_time":"2024-09-16T01:08:24+00:00","og_image":[{"url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/","url":"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/","name":"Les intervenants du congr\u00e8s - The Fourth Lausanne Congress","isPartOf":{"@id":"https:\/\/congress.lausanne.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/#primaryimage"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/#primaryimage"},"thumbnailUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye.jpg","datePublished":"2024-09-09T02:01:27+00:00","dateModified":"2024-09-16T01:08:24+00:00","breadcrumb":{"@id":"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/#primaryimage","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye.jpg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/speaker-Femi-B-Adeleye.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/congress.lausanne.org\/fr\/les-intervenants-du-congres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/congress.lausanne.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les intervenants du congr\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/congress.lausanne.org\/fr\/#website","url":"https:\/\/congress.lausanne.org\/fr\/","name":"The Fourth Lausanne Congress","description":"","publisher":{"@id":"https:\/\/congress.lausanne.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/congress.lausanne.org\/fr\/#organization","name":"The Fourth Lausanne Congress","url":"https:\/\/congress.lausanne.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","width":1477,"height":266,"caption":"The Fourth Lausanne Congress"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/comments?post=9563"}],"version-history":[{"count":0,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9563\/revisions"}],"wp:attachment":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/media?parent=9563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":9654,"date":"2024-08-27T05:44:47","date_gmt":"2024-08-27T05:44:47","guid":{"rendered":"https:\/\/congress.lausanne.org\/packing-list-fr\/"},"modified":"2024-09-16T03:40:25","modified_gmt":"2024-09-16T03:40:25","slug":"packing-list-fr","status":"publish","type":"page","link":"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/","title":{"rendered":"Votre guide des indispensables pour le quatri\u00e8me congr\u00e8s de Lausanne"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-media-text is-stacked-on-mobile is-image-fill\"><figure class=\"wp-block-media-text__media\" style=\"background-image:url(https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg);background-position:50% 50%\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg\" alt=\"\" class=\"wp-image-7485 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<div style=\"height:1em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Impatient de participer au quatri\u00e8me congr\u00e8s de Lausanne ? Pr\u00e9parons-nous !<\/h3>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-default, text-divider\" style=\"background-color:#0003ff;color:#0003ff\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Pour que votre exp\u00e9rience soit aussi fluide et enrichissante que possible, nous avons compil\u00e9 une liste de bagages pour vous faciliter la t\u00e2che. Que vous veniez de l&rsquo;autre bout du monde ou du coin de la rue, nous esp\u00e9rons que ce guide vous aidera \u00e0 pr\u00e9parer votre voyage et \u00e0 tirer le meilleur parti de votre s\u00e9jour au Congr\u00e8s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N&rsquo;h\u00e9sitez pas \u00e0 t\u00e9l\u00e9charger et \u00e0 imprimer cette liste de v\u00e9rification, et n&rsquo;oubliez pas de laisser un peu de place dans votre valise pour les b\u00e9n\u00e9dictions et les opportunit\u00e9s inattendues qui accompagnent ce rassemblement unique !<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-93a3ad6c wp-block-group-is-layout-flex\">\n<div style=\"height:2em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-42fb7c7f\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center\" style=\"text-transform:uppercase\">Vos indispensables : <\/h3>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-text-color has-alpha-channel-opacity has-background is-style-default, text-divider\" style=\"background-color:#0003ff;color:#0003ff\"\/>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:2em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-42fb7c7f\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:35% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Passport-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-7492 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Passport-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Passport-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Passport-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Passport-1-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Passport-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<div style=\"height:1em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"text-transform:uppercase\">Documents de voyage<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Passeport valide avec au moins 6 mois de validit\u00e9<\/li>\n\n\n\n<li>Visa (le cas \u00e9ch\u00e9ant)<\/li>\n\n\n\n<li>Informations relatives \u00e0 l&rsquo;assurance voyage (le cas \u00e9ch\u00e9ant)<\/li>\n\n\n\n<li>Itin\u00e9raire de vol (copie num\u00e9rique ou imprim\u00e9e)<\/li>\n\n\n\n<li>Copies imprim\u00e9es des documents importants (passeport, visa, assurance)<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:auto 35%\"><div class=\"wp-block-media-text__content\">\n<div style=\"height:1em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"text-transform:uppercase\"><strong>Informations sur l&rsquo;h\u00e9bergement<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Confirmation de la r\u00e9servation de l&rsquo;h\u00f4tel<\/li>\n\n\n\n<li>Coordonn\u00e9es de l&rsquo;h\u00f4tel, notamment le nom, l&rsquo;adresse et le num\u00e9ro de t\u00e9l\u00e9phone de l&rsquo;h\u00f4tel<\/li>\n<\/ul>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Navigation-2-1024x1024.jpg\" alt=\"\" class=\"wp-image-7507 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Navigation-2-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Navigation-2-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Navigation-2-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Navigation-2-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Navigation-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:35% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Personal-Essentials-1024x1024.jpg\" alt=\"\" class=\"wp-image-7514 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Personal-Essentials-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Personal-Essentials-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Personal-Essentials-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Personal-Essentials-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Personal-Essentials.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<div style=\"height:1em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"text-transform:uppercase\"><strong>Effets personnels n\u00e9cessaires<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Des v\u00eatements adapt\u00e9s \u00e0 la dur\u00e9e du congr\u00e8s (v\u00eatements d&rsquo;affaires d\u00e9contract\u00e9s)<\/li>\n\n\n\n<li>Tenue culturelle pour le mardi soir (facultatif, mais encourag\u00e9 !)<\/li>\n\n\n\n<li>Chaussures confortables<\/li>\n\n\n\n<li>V\u00eatements d&rsquo;ext\u00e9rieur adapt\u00e9s aux conditions m\u00e9t\u00e9orologiques\n<ul class=\"wp-block-list\">\n<li>En septembre, la Cor\u00e9e du Sud conna\u00eet un m\u00e9lange de temp\u00e9ratures chaudes et fra\u00eeches, alors que le pays passe de l&rsquo;\u00e9t\u00e9 \u00e0 l&rsquo;automne. Si les temp\u00e9ratures diurnes peuvent encore \u00eatre assez chaudes, surtout au d\u00e9but du mois, les soir\u00e9es et les matin\u00e9es peuvent \u00eatre plus fra\u00eeches. Un pull l\u00e9ger ou une veste est conseill\u00e9 pour les p\u00e9riodes plus fra\u00eeches, et une veste de pluie ou un parapluie peuvent \u00eatre utiles pour les averses occasionnelles. V\u00e9rifier les pr\u00e9visions m\u00e9t\u00e9orologiques avant votre voyage vous aidera \u00e0 faire vos valises de mani\u00e8re appropri\u00e9e et \u00e0 vous tenir pr\u00eat pour tout changement de temps.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Trousse de toilette et m\u00e9dicaments<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:auto 35%\"><div class=\"wp-block-media-text__content\">\n<div style=\"height:1em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"text-transform:uppercase\"><strong>Technologie et communication<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>T\u00e9l\u00e9phone portable et chargeur<\/li>\n\n\n\n<li>Ordinateur portable ou tablette et chargeur<\/li>\n\n\n\n<li>Adaptateur universel de voyage (ou adaptateur compatible avec les prises de type C et de type F)<\/li>\n\n\n\n<li>Casque ou \u00e9couteurs (indispensables pour les non-anglophones)<\/li>\n\n\n\n<li>Application de traduction (utile pour les non-anglophones)<\/li>\n\n\n\n<li>Carte et itin\u00e9raire pour se rendre sur place<\/li>\n\n\n\n<li>Nous vous recommandons de t\u00e9l\u00e9charger <strong>Naver Maps<\/strong> pour une navigation fiable en Cor\u00e9e du Sud. Soyez pr\u00e9voyant et faites une capture d&rsquo;\u00e9cran de vos indications au cas o\u00f9 votre t\u00e9l\u00e9phone perdrait sa connexion.\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/apps.apple.com\/us\/app\/naver-map-navigation\/id311867728\">Naver Maps Apple App Store<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.nhn.android.nmap&amp;hl=en\">Naver Maps Google Play Store<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Gadgets-1024x1024.jpg\" alt=\"\" class=\"wp-image-7521 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Gadgets-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Gadgets-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Gadgets-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Gadgets-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Gadgets.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:35% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Emergency-Contact-1024x1024.jpg\" alt=\"\" class=\"wp-image-7528 size-full\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Emergency-Contact-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Emergency-Contact-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Emergency-Contact-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Emergency-Contact-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Emergency-Contact.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<div style=\"height:1em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"text-transform:uppercase\"><strong>Pr\u00e9paration aux situations d&rsquo;urgence<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Num\u00e9ro de contact en cas d&rsquo;urgence (\u00e0 n&rsquo;utiliser qu&rsquo;en cas d&rsquo;urgence)<\/li>\n\n\n\n<li>Coordonn\u00e9es de l&rsquo;ambassade locale<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:2em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-42fb7c7f\"><\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-background wp-block-paragraph\" style=\"background-color:#e6eaec\"><strong>Note :<\/strong> Il s&rsquo;agit d&rsquo;une liste de bagages sugg\u00e9r\u00e9e pour vous aider \u00e0 pr\u00e9parer le Congr\u00e8s. Veuillez v\u00e9rifier les politiques et r\u00e9glementations des pays concern\u00e9s pour vous assurer que tous les articles que vous pr\u00e9voyez d&rsquo;apporter sont autoris\u00e9s. Bon voyage !<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Impatient de participer au quatri\u00e8me congr\u00e8s de Lausanne ? Pr\u00e9parons-nous ! Pour que votre exp\u00e9rience soit aussi fluide et enrichissante que possible, nous avons compil\u00e9 une liste de bagages pour vous faciliter la t\u00e2che. Que vous veniez de l&rsquo;autre bout du monde ou du coin de la rue, nous&#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9654","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Votre guide des indispensables pour le quatri\u00e8me congr\u00e8s de Lausanne - The Fourth Lausanne Congress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Votre guide des indispensables pour le quatri\u00e8me congr\u00e8s de Lausanne - The Fourth Lausanne Congress\" \/>\n<meta property=\"og:description\" content=\"Impatient de participer au quatri\u00e8me congr\u00e8s de Lausanne ? Pr\u00e9parons-nous ! Pour que votre exp\u00e9rience soit aussi fluide et enrichissante que possible, nous avons compil\u00e9 une liste de bagages pour vous faciliter la t\u00e2che. Que vous veniez de l&rsquo;autre bout du monde ou du coin de la rue, nous...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"The Fourth Lausanne Congress\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T03:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/\",\"name\":\"Votre guide des indispensables pour le quatri\u00e8me congr\u00e8s de Lausanne - The Fourth Lausanne Congress\",\"isPartOf\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg\",\"datePublished\":\"2024-08-27T05:44:47+00:00\",\"dateModified\":\"2024-09-16T03:40:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/#primaryimage\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/congress.lausanne.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Votre guide des indispensables pour le quatri\u00e8me congr\u00e8s de Lausanne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"name\":\"The Fourth Lausanne Congress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\",\"name\":\"The Fourth Lausanne Congress\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"width\":1477,\"height\":266,\"caption\":\"The Fourth Lausanne Congress\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Votre guide des indispensables pour le quatri\u00e8me congr\u00e8s de Lausanne - The Fourth Lausanne Congress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Votre guide des indispensables pour le quatri\u00e8me congr\u00e8s de Lausanne - The Fourth Lausanne Congress","og_description":"Impatient de participer au quatri\u00e8me congr\u00e8s de Lausanne ? Pr\u00e9parons-nous ! Pour que votre exp\u00e9rience soit aussi fluide et enrichissante que possible, nous avons compil\u00e9 une liste de bagages pour vous faciliter la t\u00e2che. Que vous veniez de l&rsquo;autre bout du monde ou du coin de la rue, nous...","og_url":"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/","og_site_name":"The Fourth Lausanne Congress","article_modified_time":"2024-09-16T03:40:25+00:00","og_image":[{"url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/","url":"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/","name":"Votre guide des indispensables pour le quatri\u00e8me congr\u00e8s de Lausanne - The Fourth Lausanne Congress","isPartOf":{"@id":"https:\/\/congress.lausanne.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/#primaryimage"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/#primaryimage"},"thumbnailUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg","datePublished":"2024-08-27T05:44:47+00:00","dateModified":"2024-09-16T03:40:25+00:00","breadcrumb":{"@id":"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/#primaryimage","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Packing-2-1024x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/congress.lausanne.org\/fr\/packing-list-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/congress.lausanne.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Votre guide des indispensables pour le quatri\u00e8me congr\u00e8s de Lausanne"}]},{"@type":"WebSite","@id":"https:\/\/congress.lausanne.org\/fr\/#website","url":"https:\/\/congress.lausanne.org\/fr\/","name":"The Fourth Lausanne Congress","description":"","publisher":{"@id":"https:\/\/congress.lausanne.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/congress.lausanne.org\/fr\/#organization","name":"The Fourth Lausanne Congress","url":"https:\/\/congress.lausanne.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","width":1477,"height":266,"caption":"The Fourth Lausanne Congress"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/comments?post=9654"}],"version-history":[{"count":0,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9654\/revisions"}],"wp:attachment":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/media?parent=9654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":9647,"date":"2024-08-27T05:44:08","date_gmt":"2024-08-27T05:44:08","guid":{"rendered":"https:\/\/congress.lausanne.org\/?page_id=9647"},"modified":"2024-09-16T02:08:22","modified_gmt":"2024-09-16T02:08:22","slug":"bienvenue-a-incheon-votre-arrivee-facilitee","status":"publish","type":"page","link":"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/","title":{"rendered":"Bienvenue \u00e0 Incheon : Votre arriv\u00e9e facilit\u00e9e"},"content":{"rendered":"\n<div class=\"wp-block-cover has-parallax cover has-white-color has-text-color has-link-color wp-elements-6884885625d7eddb89ca8297881c4f96\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#787878;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><div class=\"wp-block-cover__image-background wp-image-7538 has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Incheon-Airport-1-1-scaled.jpg)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div style=\"height:2em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50px\">\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:112px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\uc548\ub155\ud558\uc138\uc694 (Annyeong haseyo) <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour que votre arriv\u00e9e se passe le mieux possible, nous vous indiquons les principales \u00e9tapes \u00e0 suivre une fois que vous aurez atterri \u00e0 l&rsquo;a\u00e9roport international d&rsquo;Incheon.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:300px\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n\n\n\n<div style=\"height:2em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px\">1. D\u00e9barquer de l&rsquo;avion<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s l&rsquo;atterrissage de votre avion, attendez que le signal de port de la ceinture s&rsquo;\u00e9teigne avant de rassembler vos affaires. \u00c0 la sortie de l&rsquo;avion, suivez les panneaux \u00ab Arrivals \u00bb. Les panneaux sont en cor\u00e9en et en anglais, ce qui facilite l&rsquo;orientation.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px\">2. Remplir les formulaires d&rsquo;arriv\u00e9e<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous vous rendrez dans la zone d&rsquo;immigration, vous devrez probablement remplir divers formulaires. Il s&rsquo;agit notamment de la carte d&rsquo;arriv\u00e9e, qui vous demandera des informations telles que le nom, l&rsquo;adresse et le num\u00e9ro de t\u00e9l\u00e9phone de votre h\u00f4tel.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"401\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card.jpg\" alt=\"\" class=\"wp-image-8263\" style=\"width:445px;height:auto\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card.jpg 595w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card-300x202.jpg 300w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/60d19ced763cb7001ef6e24f-694x1024.jpg\" alt=\"\" class=\"wp-image-8256\" style=\"width:204px;height:auto\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/60d19ced763cb7001ef6e24f-694x1024.jpg 694w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/60d19ced763cb7001ef6e24f-203x300.jpg 203w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/60d19ced763cb7001ef6e24f.jpg 720w\" sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"537\" height=\"700\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/img_tax_declaration_immigration_01_en.png\" alt=\"\" class=\"wp-image-8277\" style=\"width:230px;height:auto\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/img_tax_declaration_immigration_01_en.png 537w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/img_tax_declaration_immigration_01_en-230x300.png 230w\" sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, des formulaires de d\u00e9claration de sant\u00e9 peuvent \u00eatre requis en cas d&rsquo;avis sanitaire. Vous pouvez remplir le formulaire de d\u00e9claration de sant\u00e9 \u00e0 l&rsquo;avance sur ce <a href=\"https:\/\/qcode.kdca.go.kr\/qco\/index.do\" target=\"_blank\" rel=\"noreferrer noopener\">site web<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous transportez des articles qui doivent \u00eatre d\u00e9clar\u00e9s (comme de grosses sommes d&rsquo;argent ou des marchandises sp\u00e9cifiques), veillez \u00e0 les indiquer avec pr\u00e9cision sur le formulaire de d\u00e9claration en douane afin de vous conformer \u00e0 la r\u00e9glementation.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px\">3. Proc\u00e9dures d&rsquo;immigration et de quarantaine<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ensuite, rendez-vous aux guichets de l&rsquo;immigration. Vous devrez pr\u00e9senter votre passeport, votre visa et le formulaire de d\u00e9claration de douane d\u00fbment rempli \u00e0 l&rsquo;agent d&rsquo;immigration. Si vous avez une carte d&rsquo;arriv\u00e9e (souvent distribu\u00e9e dans l&rsquo;avion), pr\u00e9parez-la \u00e9galement. L&rsquo;agent vous posera peut-\u00eatre quelques questions sur votre s\u00e9jour en Cor\u00e9e ; r\u00e9pondez-y calmement et honn\u00eatement. S&rsquo;il y a des exigences de quarantaine (comme un examen de sant\u00e9), vous serez dirig\u00e9 vers une zone s\u00e9par\u00e9e pour un contr\u00f4le rapide.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00eame si vous disposez d&rsquo;un visa, soyez pr\u00eat \u00e0 faire face \u00e0 d&rsquo;\u00e9ventuels probl\u00e8mes au guichet d&rsquo;immigration de l&rsquo;a\u00e9roport d&rsquo;Incheon. Assurez-vous d&rsquo;avoir \u00e0 port\u00e9e de main <strong>votre lettre d&rsquo;invitation au Congr\u00e8s de Lausanne, vos billets d&rsquo;avion aller-retour et votre bon d&rsquo;h\u00f4tel (ou l&rsquo;adresse de votre logement)<\/strong>. Veuillez vous r\u00e9f\u00e9rer au courriel qui vous a \u00e9t\u00e9 envoy\u00e9 pour obtenir le num\u00e9ro de contact du service d&rsquo;assistance au cas o\u00f9 vous rencontreriez des probl\u00e8mes au guichet d&rsquo;immigration de l&rsquo;a\u00e9roport.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px\">4. R\u00e9cup\u00e9rez vos bagages<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez enregistr\u00e9 des bagages avant votre vol, vous devrez les r\u00e9clamer \u00e0 l&rsquo;arriv\u00e9e \u00e0 la zone de r\u00e9cup\u00e9ration des bagages. Une fois que vous avez pass\u00e9 l&rsquo;immigration, suivez les panneaux indiquant la zone de r\u00e9cup\u00e9ration des bagages. Recherchez votre num\u00e9ro de vol sur les \u00e9crans d&rsquo;affichage \u00e9lectroniques pour trouver le bon carrousel. Si vous ne savez pas sur quel carrousel se trouvent vos bagages, demandez \u00e0 une h\u00f4tesse de l&rsquo;air lorsque vous descendez de l&rsquo;avion. R\u00e9cup\u00e9rez vos bagages, en vous assurant que vous avez tous vos effets personnels avant de repartir. Si vos bagages n&rsquo;arrivent pas, rendez-vous au service des bagages perdus pour obtenir de l&rsquo;aide.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px\">5. Inspection douani\u00e8re<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Vos bagages en main, dirigez-vous vers la zone d&rsquo;inspection douani\u00e8re. Vous devrez peut-\u00eatre pr\u00e9senter \u00e0 nouveau votre formulaire de d\u00e9claration de douane. Si vous avez des articles \u00e0 d\u00e9clarer, vous serez dirig\u00e9 vers un couloir sp\u00e9cifique pour l&rsquo;inspection. Sinon, vous pouvez emprunter le couloir \u00ab Rien \u00e0 d\u00e9clarer \u00bb (\u00ab\u00a0nothing to declare\u00a0\u00bb).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px\">6. Rencontrez vos b\u00e9n\u00e9voles<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir pass\u00e9 la douane, vous entrerez dans le hall des arriv\u00e9es. Cherchez notre b\u00e9n\u00e9vole qui tient une pancarte avec le logo du Congr\u00e8s de Lausanne. Ils sont l\u00e0 pour r\u00e9pondre \u00e0 vos questions et vous guider vers votre prochaine destination. Si vous avez besoin de changer de l&rsquo;argent, des guichets sont \u00e0 votre disposition et nos b\u00e9n\u00e9voles peuvent vous y orienter.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px\">7. Conseils pratiques concernant les transports<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous arrivez le 21 ou le 22 septembre entre 9h00 et 22h00 et que vous s\u00e9journez dans un h\u00f4tel r\u00e9pertori\u00e9, vous pouvez utiliser <a href=\"https:\/\/congress.lausanne.org\/shuttles\/\" target=\"_blank\" rel=\"noreferrer noopener\">le service<\/a> de navette qui fonctionnera selon un horaire fixe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Emplacement des navettes \u00e0 l&rsquo;a\u00e9roport d&rsquo;Incheon<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Terminal 1<\/strong> : Apr\u00e8s la zone de r\u00e9cup\u00e9ration des bagages, se rendre \u00e0 la <strong>porte 13(1F)<\/strong> pour l&#8217;emplacement de la navette au stand d&rsquo;accueil de Lausanne.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/shuttles-incheon-airport-terminal-1-1024x768.jpg\" alt=\"\" class=\"wp-image-8286\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/shuttles-incheon-airport-terminal-1-1024x768.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/shuttles-incheon-airport-terminal-1-300x225.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/shuttles-incheon-airport-terminal-1-768x576.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/shuttles-incheon-airport-terminal-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Terminal 2<\/strong> : Apr\u00e8s la zone de r\u00e9cup\u00e9ration des bagages, se rendre \u00e0 la <strong>porte 7(1F)<\/strong> pour l&#8217;emplacement de la navette au stand d&rsquo;accueil de Lausanne.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/shuttles-incheon-airport-terminal-2-1024x768.jpg\" alt=\"\" class=\"wp-image-8293\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/shuttles-incheon-airport-terminal-2-1024x768.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/shuttles-incheon-airport-terminal-2-300x225.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/shuttles-incheon-airport-terminal-2-768x576.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/shuttles-incheon-airport-terminal-2.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Sinon, plusieurs options de transport sont disponibles pour vous conduire de l&rsquo;a\u00e9roport \u00e0 votre logement:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Taxis<\/strong> : Des taxis officiels sont disponibles \u00e0 l&rsquo;ext\u00e9rieur du hall des arriv\u00e9es. Veillez \u00e0 n&rsquo;utiliser que des taxis officiels afin d&rsquo;\u00e9viter tout probl\u00e8me potentiel. Notre b\u00e9n\u00e9vole peut vous aider \u00e0 vous rendre \u00e0 la station de taxis et s&rsquo;assurer que vous montiez dans le bon v\u00e9hicule.<\/li>\n\n\n\n<li><strong>Airport Railroad Express (AREX)<\/strong> : C&rsquo;est un moyen rapide et pratique de se rendre \u00e0 S\u00e9oul. L&rsquo;AREX est directement reli\u00e9 \u00e0 la gare de S\u00e9oul, o\u00f9 vous pouvez prendre d&rsquo;autres lignes de m\u00e9tro. Les billets peuvent \u00eatre achet\u00e9s \u00e0 des machines ou \u00e0 des guichets pr\u00e8s de l&rsquo;entr\u00e9e, et notre b\u00e9n\u00e9vole peut vous y aider.<\/li>\n\n\n\n<li><strong>Bus<\/strong> : L&rsquo;a\u00e9roport d&rsquo;Incheon est bien desservi par des bus qui se rendent dans diff\u00e9rentes parties de S\u00e9oul et au-del\u00e0. Notre b\u00e9n\u00e9vole peut vous aider \u00e0 choisir le bon bus pour votre destination et vous aider \u00e0 acheter les billets.<\/li>\n\n\n\n<li><strong>Services de covoiturage <\/strong>: Des applications de covoiturage sont \u00e9galement disponibles en Cor\u00e9e, et notre b\u00e9n\u00e9vole peut vous guider dans leur utilisation.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px\">8. Conseils suppl\u00e9mentaires<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cartes SIM et Wi-Fi <\/strong>: si vous avez besoin d&rsquo;une carte SIM locale ou d&rsquo;un appareil Wi-Fi portable, vous trouverez des kiosques dans le hall des arriv\u00e9es. Ils vous aideront \u00e0 rester connect\u00e9 pendant votre s\u00e9jour. Le co\u00fbt est d&rsquo;environ 35 dollars pour un forfait de 10 jours.<\/li>\n\n\n\n<li><strong>Change de monnaie<\/strong> : Les cartes Mastercard et Visa \u00e9tant largement accept\u00e9es, vous n&rsquo;aurez peut-\u00eatre pas besoin d&rsquo;argent liquide. Si vous souhaitez \u00e9changer de l&rsquo;argent \u00e0 l&rsquo;a\u00e9roport pour des d\u00e9penses imm\u00e9diates telles que le transport, des comptoirs de change sont situ\u00e9s dans le hall des arriv\u00e9es.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>1. D\u00e9barquer de l&rsquo;avion Apr\u00e8s l&rsquo;atterrissage de votre avion, attendez que le signal de port de la ceinture s&rsquo;\u00e9teigne avant de rassembler vos affaires. \u00c0 la sortie de l&rsquo;avion, suivez les panneaux \u00ab Arrivals \u00bb. Les panneaux sont en cor\u00e9en et en anglais, ce qui facilite l&rsquo;orientation. 2. Remplir&#8230;<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9647","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bienvenue \u00e0 Incheon : Votre arriv\u00e9e facilit\u00e9e - The Fourth Lausanne Congress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bienvenue \u00e0 Incheon : Votre arriv\u00e9e facilit\u00e9e - The Fourth Lausanne Congress\" \/>\n<meta property=\"og:description\" content=\"1. D\u00e9barquer de l&rsquo;avion Apr\u00e8s l&rsquo;atterrissage de votre avion, attendez que le signal de port de la ceinture s&rsquo;\u00e9teigne avant de rassembler vos affaires. \u00c0 la sortie de l&rsquo;avion, suivez les panneaux \u00ab Arrivals \u00bb. Les panneaux sont en cor\u00e9en et en anglais, ce qui facilite l&rsquo;orientation. 2. Remplir...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/\" \/>\n<meta property=\"og:site_name\" content=\"The Fourth Lausanne Congress\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T02:08:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/\",\"name\":\"Bienvenue \u00e0 Incheon : Votre arriv\u00e9e facilit\u00e9e - The Fourth Lausanne Congress\",\"isPartOf\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card.jpg\",\"datePublished\":\"2024-08-27T05:44:08+00:00\",\"dateModified\":\"2024-09-16T02:08:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/#primaryimage\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card.jpg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/congress.lausanne.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bienvenue \u00e0 Incheon : Votre arriv\u00e9e facilit\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"name\":\"The Fourth Lausanne Congress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\",\"name\":\"The Fourth Lausanne Congress\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"width\":1477,\"height\":266,\"caption\":\"The Fourth Lausanne Congress\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bienvenue \u00e0 Incheon : Votre arriv\u00e9e facilit\u00e9e - The Fourth Lausanne Congress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/","og_locale":"fr_FR","og_type":"article","og_title":"Bienvenue \u00e0 Incheon : Votre arriv\u00e9e facilit\u00e9e - The Fourth Lausanne Congress","og_description":"1. D\u00e9barquer de l&rsquo;avion Apr\u00e8s l&rsquo;atterrissage de votre avion, attendez que le signal de port de la ceinture s&rsquo;\u00e9teigne avant de rassembler vos affaires. \u00c0 la sortie de l&rsquo;avion, suivez les panneaux \u00ab Arrivals \u00bb. Les panneaux sont en cor\u00e9en et en anglais, ce qui facilite l&rsquo;orientation. 2. Remplir...","og_url":"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/","og_site_name":"The Fourth Lausanne Congress","article_modified_time":"2024-09-16T02:08:22+00:00","og_image":[{"url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/","url":"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/","name":"Bienvenue \u00e0 Incheon : Votre arriv\u00e9e facilit\u00e9e - The Fourth Lausanne Congress","isPartOf":{"@id":"https:\/\/congress.lausanne.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/#primaryimage"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/#primaryimage"},"thumbnailUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card.jpg","datePublished":"2024-08-27T05:44:08+00:00","dateModified":"2024-09-16T02:08:22+00:00","breadcrumb":{"@id":"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/#primaryimage","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card.jpg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/09\/3_arrival_card.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/congress.lausanne.org\/fr\/bienvenue-a-incheon-votre-arrivee-facilitee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/congress.lausanne.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Bienvenue \u00e0 Incheon : Votre arriv\u00e9e facilit\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/congress.lausanne.org\/fr\/#website","url":"https:\/\/congress.lausanne.org\/fr\/","name":"The Fourth Lausanne Congress","description":"","publisher":{"@id":"https:\/\/congress.lausanne.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/congress.lausanne.org\/fr\/#organization","name":"The Fourth Lausanne Congress","url":"https:\/\/congress.lausanne.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","width":1477,"height":266,"caption":"The Fourth Lausanne Congress"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/comments?post=9647"}],"version-history":[{"count":0,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/9647\/revisions"}],"wp:attachment":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/media?parent=9647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6609,"date":"2024-06-24T00:42:03","date_gmt":"2024-06-24T00:42:03","guid":{"rendered":"https:\/\/congress.lausanne.org\/?page_id=6609"},"modified":"2024-09-16T06:26:43","modified_gmt":"2024-09-16T06:26:43","slug":"vx","status":"publish","type":"page","link":"https:\/\/congress.lausanne.org\/fr\/vx\/","title":{"rendered":"Exp\u00e9rience virtuelle du Congr\u00e8s"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover\" style=\"min-height:35vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-black-background-color has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" class=\"wp-block-cover__image-background wp-image-6285\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG.jpg 1920w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG-300x169.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG-1024x576.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG-768x432.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG-1536x864.jpg 1536w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG-1400x788.jpg 1400w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center vx-em has-white-color has-text-color has-link-color wp-elements-edb806a8441e511eb1892f6e349de6d1 wp-block-paragraph\"><em>Connecter. Collaborer. Congr\u00e8s VX<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1619\" height=\"758\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-satelite-vx-black-icon-12.png\" alt=\"\" class=\"wp-image-6141\" style=\"width:200px\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-satelite-vx-black-icon-12.png 1619w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-satelite-vx-black-icon-12-300x140.png 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-satelite-vx-black-icon-12-1024x479.png 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-satelite-vx-black-icon-12-768x360.png 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-satelite-vx-black-icon-12-1536x719.png 1536w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-satelite-vx-black-icon-12-1400x655.png 1400w\" sizes=\"auto, (max-width: 1619px) 100vw, 1619px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-black-color has-white-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/journey.lausanne.org\/register-for-vx\/?locale=fr\">Proposez des noms pour l\u2019exp\u00e9rience de la cohorte virtuelle de S\u00e9oul<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-left\"><strong>Participez \u00e0 S\u00e9oul 2024 o\u00f9 que vous soyez<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">En \u00e9largissant l\u2019espace au-del\u00e0 des murs de Songdo Convensia, toute l\u2019\u00c9glise a la possibilit\u00e9 de participer \u00e0 S\u00e9oul-Incheon 2024. Participants virtuel, vous avez la possibilit\u00e9 de participer \u00e0 S\u00e9oul-Incheon 2024 d\u2019o\u00f9 que vous soyez, ce qui fait que la famille, le travail, et les obstacles financiers sont moindres pour participer \u00e0 cet \u00e9v\u00e9nement qui n\u2019arrive qu\u2019une fois par g\u00e9n\u00e9ration.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Qu\u2019est-ce que le Congr\u00e8s VX&nbsp;?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019Exp\u00e9rience virtuelle du Congr\u00e8s (VX) est une exp\u00e9rience num\u00e9rique intentionnelle et int\u00e9gr\u00e9e du Quatri\u00e8me congr\u00e8s de Lausanne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les personnes participant au congr\u00e8s virtuellement, davantage d\u2019occasions d\u2019action collaborative peuvent \u00e9merger provenant d\u2019un plus grand nombre de personnes et de lieux dans le monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;V&nbsp;\u00bb repr\u00e9sente le paysage virtuel o\u00f9 les domaines num\u00e9riques fusionnement avec l\u2019impact du monde r\u00e9el, ce qui nous permet de cr\u00e9er des liens qui r\u00e9sonnent d\u2019un continent \u00e0 l\u2019autre et d\u2019une culture \u00e0 l\u2019autre. \u00ab&nbsp;X&nbsp;\u00bb symbolise la nature exp\u00e9rimentale et les possibilit\u00e9s infinies d\u2019impact et de port\u00e9e que peut offrir le monde num\u00e9rique.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-fr-01.jpg\" alt=\"\" class=\"wp-image-6652\" style=\"object-fit:cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-fr-01.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-fr-01-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-fr-01-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/v-fr-01.jpg\" alt=\"\" class=\"wp-image-6659\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/v-fr-01.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/v-fr-01-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/v-fr-01-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/x-fr-01.jpg\" alt=\"\" class=\"wp-image-6666\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/x-fr-01.jpg 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/x-fr-01-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/x-fr-01-150x150.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Bien plus qu&rsquo;un flux passif en direct, l\u2019exp\u00e9rience virtuelle offre souplesse, interaction, opportunit\u00e9s de mise en r\u00e9seau, ateliers collaboratifs et outils de participation pour permettre aux participants un engagement actif, des liens et une contribution \u00e0 la conversation autour de la mission mondiale.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Frais de participation VX<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La participation au quatri\u00e8me Congr\u00e8s de Lausanne est une exp\u00e9rience sp\u00e9ciale du genre de celles qui n\u2019arrivent qu\u2019une fois dans la vie&nbsp;! Les frais de participation de base au VX, qui comprennent les s\u00e9ances quotidiennes, la rencontre avec des milliers de chr\u00e9tiens du monde entier et bien d\u2019autres choses encore, s\u2019\u00e9l\u00e8vent \u00e0 300 USD. Cependant, nous reconnaissons que les ressources financi\u00e8res varient d\u2019un participant \u00e0 un autre et nous proposons des tarifs r\u00e9duits pour ceux qui trouveraient trop lourd le tarif de base. Ces tarifs subventionn\u00e9s sont rendus possibles gr\u00e2ce \u00e0 la g\u00e9n\u00e9rosit\u00e9 de l\u2019\u00c9glise mondiale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-group-image1-1024x1024.jpg\" alt=\"\" class=\"wp-image-6151\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-group-image1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-group-image1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-group-image1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-group-image1-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-group-image1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<h3 class=\"wp-block-heading\">Une invitation \u00e0 cheminer ensemble<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le congr\u00e8s est bien plus qu&rsquo;une simple consommation de contenu \u2013 nous souhaitons ardemment voir l&rsquo;\u00c9glise cheminer d\u2019un m\u00eame pas&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nouer des relations avec d\u2019autres participants du monde entier par le biais de groupes de discussion quotidiens, tout en \u00e9coutant ensemble un enseignement sur le livre des Actes des Ap\u00f4tres.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns reverse-col is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<h3 class=\"wp-block-heading\">Avoir un impact durable<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Collaborer les uns avec les autres, au sein de l\u2019\u00c9glise mondiale, pour combler les lacunes et saisir les opportunit\u00e9s pour annoncer l\u2019\u00c9vangile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des s\u00e9ances de collaboration seront organis\u00e9es chaque jour autour de certaines des <a href=\"https:\/\/congress.lausanne.org\/fr\/les-25-seances-collaborer-consacrees-aux-lacunes\/\">25 lacunes missionnelles<\/a> r\u00e9pertori\u00e9es. Rejoignez-nous pour susciter une action collaborative dans votre domaine d\u2019int\u00e9r\u00eat et rencontrer d\u2019autres personnes qui partagent les m\u00eames passions.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-6158\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-1-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-1-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-1-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-1-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-5-1024x1024.jpg\" alt=\"\" class=\"wp-image-6166\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-5-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-5-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-5-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-5-768x768.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-Vx-Image-5.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<h3 class=\"wp-block-heading\">Interagissez avec le Corps mondial du Christ<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Faites part de votre exp\u00e9rience et apprenez de celle des autres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrez en contact avec des croyants du monde entier gr\u00e2ce \u00e0 notre salon virtuel ouvert 24 heures sur 24, o\u00f9 vous aurez la possibilit\u00e9 d&rsquo;\u00e9changer avec d&rsquo;autres participants et des conf\u00e9renciers, et de consulter des offres virtuelles particuli\u00e8res.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-92126d18 wp-block-columns-is-layout-flex\" style=\"margin-bottom:0\">\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-61b3d17e98a5a3a33ec2a08bc1bb58de is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#e6eaec;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-plenary.png\" alt=\"\" class=\"wp-image-5735\" style=\"width:180px\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-plenary.png 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-plenary-300x300.png 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-plenary-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n<h4 class=\"wp-block-heading has-text-align-center has-text-color has-link-color wp-elements-9966cf000ec090355c29b5eb5c903aab\" style=\"color:#0000ff\"><strong>S\u00e9ances pl\u00e9ni\u00e8res<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"line-height:1.5\"><strong>Points forts des s\u00e9ances pl\u00e9ni\u00e8res et des discussions en petits groupes.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Discussions organis\u00e9es autour du Congr\u00e8s<\/li>\n\n\n\n<li>Discussions en groupes de table<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-230cdfafc98dff7b4e65c7ae8ece9f5e is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#e6eaec;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-collab.png\" alt=\"\" class=\"wp-image-5743\" style=\"width:180px\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-collab.png 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-collab-300x300.png 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-collab-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n<h4 class=\"wp-block-heading has-text-align-center has-text-color has-link-color wp-elements-9f8982ee5e8cb2932e2ebff6763ada56\" style=\"color:#ff4563\"><strong>Collaborer VX<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"line-height:1.5\"><strong>Collaborer \u00e0 combler l\u2019une des 25 lacunes list\u00e9es dans l\u2019\u00c9tat du Mandat missionnaire.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Explorer les lacunes missionnelles<\/li>\n\n\n\n<li>Se pr\u00e9parer \u00e0 l\u2019action collaborative<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-bd388e83be3fe541ffa427547feca94d is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#e6eaec;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-lounge.png\" alt=\"\" class=\"wp-image-5757\" style=\"width:180px\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-lounge.png 512w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-lounge-300x300.png 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/congress-lounge-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n<h4 class=\"wp-block-heading has-text-align-center has-text-color has-link-color wp-elements-ffd883cfa0e9e6c3eeb9cc9a6244d814\" style=\"color:#8100ff\"><strong>Salon VX<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Un espace de connexion ouvert 24 heures sur 24 et 7 jours sur 7 pendant la semaine du congr\u00e8s.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mise en r\u00e9seau avec d&rsquo;autres participants<\/li>\n\n\n\n<li>\u00c9v\u00e9nements sp\u00e9ciaux pop-up<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/08\/Virtual-VX-Congress-Participant-Orientation-Collaboration-Networking-and-the-Congress-Programme.mp4\" target=\"_blank\" rel=\"noreferrer noopener\">Aper\u00e7u du Salon VX<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Un v\u00e9cu du congr\u00e8s sur mesure<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pendant la semaine du congr\u00e8s <strong>(23-27 septembre 2024)<\/strong>, vous aurez la possibilit\u00e9 de personnaliser votre v\u00e9cu du congr\u00e8s, \u00e0 savoir, vous pourrez assister aux s\u00e9ances aux heures qui vous conviennent le mieux, quel que soit l\u2019endroit o\u00f9 vous vous trouvez.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" id=\"plenary\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" open><summary>Programme des s\u00e9ances pl\u00e9ni\u00e8res<\/summary>\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:70%\">\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>S\u00e9ances pl\u00e9ni\u00e8res<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Asie&nbsp;\/ Oc\u00e9anie <\/strong>(Sydney)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Asie du Sud-Est<\/strong> (Bangkok)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>UTC<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Afrique&nbsp;\/ Europe<\/strong> (Berlin &#8211; CEST)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Ameriques<\/strong> (New York &#8211; EDT)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Ameriques<\/strong> (Los Angeles &#8211; PDT)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Option A<\/strong><br>anglais<br>cor\u00e9en<br>mandarin<\/td><td class=\"has-text-align-center\" data-align=\"center\">17:00 \u2013<br>19:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">14:00 \u2013<br>16:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">07:00 \u2013 09:00 <\/td><td class=\"has-text-align-center\" data-align=\"center\">09:00 \u2013<br>11:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">03:00 \u2013<br>05:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">00:00 \u2013<br>02:00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Option B<\/strong><br>anglais<br>fran\u00e7ais<\/td><td class=\"has-text-align-center\" data-align=\"center\">01:00 \u2013<br>03:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">22:00 \u2013<br>00:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">15:00 \u2013<br>17:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">17:00 \u2013<br>19:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">11:00 \u2013<br>13:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">08:00 \u2013<br>10:00<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Option C<\/strong><br>anglais<br>espagnol<br>portugais<\/td><td class=\"has-text-align-center\" data-align=\"center\">07:00 \u2013<br>09:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">04:00 \u2013<br>06:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">21:00 \u2013<br>23:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">23:00 \u2013<br>01:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">17:00 \u2013<br>19:00<\/td><td class=\"has-text-align-center\" data-align=\"center\">14:00 \u2013<br>16:00<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n<\/div>\n<\/details>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" id=\"collaborate\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\" open><summary>Programme des s\u00e9ances Collaborer<\/summary>\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:70%\">\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>PLENARY SESSION<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Asie&nbsp;\/ Oc\u00e9anie <\/strong>(Sydney)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Asie du Sud-Est<\/strong> (Bangkok)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>UTC<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Afrique&nbsp;\/ Europe<\/strong> (Berlin &#8211; CEST)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Ameriques<\/strong> (New York &#8211; EDT)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Ameriques<\/strong> (Los Angeles &#8211; PDT)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Option A<\/strong><br>Lacunes s\u00e9lectionn\u00e9es<\/td><td class=\"has-text-align-center\" data-align=\"center\">09:00 \u2013<br>10:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">06:00 \u2013<br>07:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">23:00 \u2013<br>00:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">01:00 \u2013<br>02:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">19:00 \u2013<br>20:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">16:00 \u2013<br>17:30<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Option B<\/strong><br>Lacunes s\u00e9lectionn\u00e9es<\/td><td class=\"has-text-align-center\" data-align=\"center\">15:00 \u2013<br>16:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">12:00 \u2013<br>13:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">05:00 \u2013<br>06:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">07:00 \u2013<br>08:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">01:00 \u2013<br>02:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">22:00 \u2013<br>23:30<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Option C<\/strong><br>Lacunes s\u00e9lectionn\u00e9es<\/td><td class=\"has-text-align-center\" data-align=\"center\">23:00 \u2013<br>00:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">20:00 \u2013<br>12:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">13:00 \u2013<br>14:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">15:00 \u2013<br>16:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">09:00 \u2013<br>10:30<\/td><td class=\"has-text-align-center\" data-align=\"center\">06:00 \u2013<br>07:30<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n<\/div>\n<\/details>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Int\u00e9ress\u00e9(e) \u00e0 offrir votre service au Congr\u00e8s VX&nbsp;? V\u00e9rifier ici les postes \u00e0 pourvoir.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/congress.lausanne.org\/serve\/\">Voir les postes de b\u00e9n\u00e9voles VX \u00e0 pourvoir<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Participez \u00e0 S\u00e9oul 2024 o\u00f9 que vous soyez En \u00e9largissant l\u2019espace au-del\u00e0 des murs de Songdo Convensia, toute l\u2019\u00c9glise a la possibilit\u00e9 de participer \u00e0 S\u00e9oul-Incheon 2024. Participants virtuel, vous avez la possibilit\u00e9 de participer \u00e0 S\u00e9oul-Incheon 2024 d\u2019o\u00f9 que vous soyez, ce qui fait que la famille, le&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6609","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exp\u00e9rience virtuelle du Congr\u00e8s - The Fourth Lausanne Congress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/congress.lausanne.org\/fr\/vx\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exp\u00e9rience virtuelle du Congr\u00e8s - The Fourth Lausanne Congress\" \/>\n<meta property=\"og:description\" content=\"Participez \u00e0 S\u00e9oul 2024 o\u00f9 que vous soyez En \u00e9largissant l\u2019espace au-del\u00e0 des murs de Songdo Convensia, toute l\u2019\u00c9glise a la possibilit\u00e9 de participer \u00e0 S\u00e9oul-Incheon 2024. Participants virtuel, vous avez la possibilit\u00e9 de participer \u00e0 S\u00e9oul-Incheon 2024 d\u2019o\u00f9 que vous soyez, ce qui fait que la famille, le...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/congress.lausanne.org\/fr\/vx\/\" \/>\n<meta property=\"og:site_name\" content=\"The Fourth Lausanne Congress\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T06:26:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/vx\/\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/vx\/\",\"name\":\"Exp\u00e9rience virtuelle du Congr\u00e8s - The Fourth Lausanne Congress\",\"isPartOf\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/vx\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/vx\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG.jpg\",\"datePublished\":\"2024-06-24T00:42:03+00:00\",\"dateModified\":\"2024-09-16T06:26:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/vx\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/congress.lausanne.org\/fr\/vx\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/vx\/#primaryimage\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG.jpg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/vx\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/congress.lausanne.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exp\u00e9rience virtuelle du Congr\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"name\":\"The Fourth Lausanne Congress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\",\"name\":\"The Fourth Lausanne Congress\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"width\":1477,\"height\":266,\"caption\":\"The Fourth Lausanne Congress\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exp\u00e9rience virtuelle du Congr\u00e8s - The Fourth Lausanne Congress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/congress.lausanne.org\/fr\/vx\/","og_locale":"fr_FR","og_type":"article","og_title":"Exp\u00e9rience virtuelle du Congr\u00e8s - The Fourth Lausanne Congress","og_description":"Participez \u00e0 S\u00e9oul 2024 o\u00f9 que vous soyez En \u00e9largissant l\u2019espace au-del\u00e0 des murs de Songdo Convensia, toute l\u2019\u00c9glise a la possibilit\u00e9 de participer \u00e0 S\u00e9oul-Incheon 2024. Participants virtuel, vous avez la possibilit\u00e9 de participer \u00e0 S\u00e9oul-Incheon 2024 d\u2019o\u00f9 que vous soyez, ce qui fait que la famille, le...","og_url":"https:\/\/congress.lausanne.org\/fr\/vx\/","og_site_name":"The Fourth Lausanne Congress","article_modified_time":"2024-09-16T06:26:43+00:00","og_image":[{"url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/congress.lausanne.org\/fr\/vx\/","url":"https:\/\/congress.lausanne.org\/fr\/vx\/","name":"Exp\u00e9rience virtuelle du Congr\u00e8s - The Fourth Lausanne Congress","isPartOf":{"@id":"https:\/\/congress.lausanne.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/congress.lausanne.org\/fr\/vx\/#primaryimage"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/vx\/#primaryimage"},"thumbnailUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG.jpg","datePublished":"2024-06-24T00:42:03+00:00","dateModified":"2024-09-16T06:26:43+00:00","breadcrumb":{"@id":"https:\/\/congress.lausanne.org\/fr\/vx\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/congress.lausanne.org\/fr\/vx\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/vx\/#primaryimage","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG.jpg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/07\/Congress-BG.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/congress.lausanne.org\/fr\/vx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/congress.lausanne.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Exp\u00e9rience virtuelle du Congr\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/congress.lausanne.org\/fr\/#website","url":"https:\/\/congress.lausanne.org\/fr\/","name":"The Fourth Lausanne Congress","description":"","publisher":{"@id":"https:\/\/congress.lausanne.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/congress.lausanne.org\/fr\/#organization","name":"The Fourth Lausanne Congress","url":"https:\/\/congress.lausanne.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","width":1477,"height":266,"caption":"The Fourth Lausanne Congress"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/6609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/comments?post=6609"}],"version-history":[{"count":0,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/6609\/revisions"}],"wp:attachment":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/media?parent=6609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6847,"date":"2024-06-21T01:02:01","date_gmt":"2024-06-21T01:02:01","guid":{"rendered":"https:\/\/congress.lausanne.org\/?page_id=6847"},"modified":"2024-08-07T01:20:39","modified_gmt":"2024-08-07T01:20:39","slug":"appels-pre-congres","status":"publish","type":"page","link":"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/","title":{"rendered":"Appels pr\u00e9-congr\u00e8s"},"content":{"rendered":"\n<div class=\"wp-block-cover cover has-white-color has-text-color has-link-color wp-elements-698dad3f6579bd11c8acf0e87132131e\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#8a6c93;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"737\" class=\"wp-block-cover__image-background wp-image-3790\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation.jpg 1920w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation-300x115.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation-1024x393.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation-768x295.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation-1536x590.jpg 1536w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation-1400x537.jpg 1400w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-7d72b555bacd578cadd43364026a0416\" style=\"font-size:1.75rem\">Bienvenue dans nos archives des appels et ateliers pour les participants sur place et virtuels au Quatri\u00e8me congr\u00e8s de Lausanne.<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Acc\u00e9dez aux enregistrements des s\u00e9ances pr\u00e9c\u00e9dentes couvrant des sujets cl\u00e9s pour vous aider \u00e0 vous pr\u00e9parer \u00e0 une exp\u00e9rience enrichissante du Congr\u00e8s.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:51px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover is-light\" style=\"min-height:175px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-100 has-background-dim\" style=\"background-color:#e6eaec\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h4 class=\"wp-block-heading has-text-align-center has-medium-font-size\"><strong>Liens rapides<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><a href=\"#all-recordings\">Tous les enregistrements<\/a> | <a href=\"#onsite\">Sur place<\/a> | <a href=\"#virtual\">Virtuel<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\" id=\"all-recordings\">Tous les enregistrements<\/h4>\n\n\n\n<details class=\"wp-block-details has-medium-font-size is-layout-flow wp-block-details-is-layout-flow\" open><summary>Voir tous les enregistrements<\/summary>\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"How to Be Missional in Your Space\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/tI3xaGGJefo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"all-recordings\" style=\"font-size:32px;text-transform:uppercase\"><a href=\"https:\/\/youtu.be\/tI3xaGGJefo\">COMMENT \u00caTRE MISSIONNEL DANS VOTRE ESPACE<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date\u00a0: 17 janvier 2024<\/li>\n\n\n\n<li>Heure\u00a0: GMT | 14h00 \u2013 15h30<\/li>\n\n\n\n<li>Anim\u00e9 par le London Institute for Contemporary Christianity (LICC)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Les participants au congr\u00e8s se sont engag\u00e9s dans cet atelier interactif dirig\u00e9 par le LICC et ont explor\u00e9 la mani\u00e8re d&rsquo;\u00eatre missionnel dans les lieux de vie quotidiens.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Serving the Persecuted Church\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/JSPNOZru9KE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:32px;text-transform:uppercase\"><a href=\"https:\/\/youtu.be\/JSPNOZru9KE\">SERVIR L&rsquo;\u00c9GLISE PERS\u00c9CUT\u00c9E<\/a><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date\u00a0: 29 f\u00e9vrier 2024<\/li>\n\n\n\n<li>Heure\u00a0: 13h00 PM GMT<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dans notre monde de plus en plus interconnect\u00e9, le sort de l&rsquo;\u00c9glise pers\u00e9cut\u00e9e ne peut \u00eatre pass\u00e9 sous silence. Que vous ayez eu une exp\u00e9rience directe ou que vous n&rsquo;ayez jamais \u00e9t\u00e9 en contact avec une personne pers\u00e9cut\u00e9e, notre atelier \u00ab\u00a0Servir l&rsquo;\u00c9glise pers\u00e9cut\u00e9e\u00a0\u00bb a permis d&rsquo;informer, d&rsquo;\u00e9duquer et de donner \u00e0 chacun les moyens de mieux servir l&rsquo;\u00c9glise de Dieu pers\u00e9cut\u00e9e pour son t\u00e9moignage en J\u00e9sus.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"24 7 Prayer Launch Event\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/3J0ekLw1JdA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px;text-transform:uppercase\"><a href=\"https:\/\/youtu.be\/3J0ekLw1JdA\">LANCEMENT DE LA PRI\u00c8RE 24 (HEURES SUR 24 ET 7 JOURS SUR )\/7<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date\u00a0: 20 mars 2024<\/li>\n\n\n\n<li>Heure\u00a0: 12h00 GMT<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Au d\u00e9but du parcours jusqu\u2019au Quatri\u00e8me congr\u00e8s, l&rsquo;\u00c9glise mondiale s&rsquo;est r\u00e9unie pour lancer une initiative de pri\u00e8re 24 heures sur 24 et 7 jours sur 7 en faveur de la mission mondiale. Les participants se sont connect\u00e9s les uns aux autres, ont pri\u00e9 avec d&rsquo;autres participants du monde entier et ont cherch\u00e9 ensemble le conseil et la b\u00e9n\u00e9diction de Dieu. Continuons \u00e0 prier pour la mission mondiale de Dieu\u00a0!<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Foundations of Collaborative Action: Workshop 1 of 3\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Ih_c6WFT5l4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px;text-transform:uppercase\"><a href=\"https:\/\/www.youtube.com\/watch?v=Ih_c6WFT5l4\">ATELIER D&rsquo;ACTION COLLABORATIVE 1 (FONDEMENTS DE L&rsquo;ACTION COLLABORATIVE)<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date\u00a0: 9 avril 2024<\/li>\n\n\n\n<li>Heure\u00a0: 14:00 PM GMT<\/li>\n\n\n\n<li>Facilit\u00e9 par Vision Synergy<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cette session, anim\u00e9e par Michael Kasper et Daniel Dow, a propos\u00e9 une r\u00e9flexion sur l&rsquo;importance de l&rsquo;unit\u00e9 et de la collaboration au sein du peuple de Dieu, avec la contribution de divers participants du monde entier.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des id\u00e9es sur la collaboration ont \u00e9t\u00e9 partag\u00e9es, notamment une discussion sur les avantages et les obstacles \u00e0 la collaboration, ainsi que sur la fa\u00e7on de surmonter les craintes associ\u00e9es aux efforts de collaboration.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Introducing the &#039;State of the Great Commission&#039; Report\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/w3I-kxB9Z9E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:32px;text-transform:uppercase\"><a href=\"https:\/\/youtu.be\/w3I-kxB9Z9E\">LANCEMENT DU RAPPORT SUR L&rsquo;\u00c9TAT DU MANDAT MISSIONNAIRE<\/a><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date\u00a0: 23 avril 2024<\/li>\n\n\n\n<li>Heure\u00a0: 13h00 GMT<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Lors de ce jalon important de notre parcours en vue de nous unir pour acc\u00e9l\u00e9rer la mission mondiale, Matthew Niermann, directeur du rapport sur l&rsquo;\u00e9tat de la Grande Commission, a pr\u00e9sent\u00e9 de mani\u00e8re experte les points saillants du rapport, offrant un aper\u00e7u du paysage actuel de l&rsquo;\u00e9vang\u00e9lisation mondiale et des voies strat\u00e9giques \u00e0 suivre. Ensemble, nous avons explor\u00e9 la profondeur de notre vocation et l&rsquo;ampleur de notre impact dans la mission mondiale de Dieu.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Proclamation Evangelism Workshop with Dr. Desmond Henry\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/JNpauGoFh2c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px;text-transform:uppercase\"><a href=\"https:\/\/youtu.be\/JNpauGoFh2c\">ATELIER D&rsquo;\u00c9VANG\u00c9LISATION PAR LA PROCLAMATION<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date\u00a0: 23 mai 2024<\/li>\n\n\n\n<li>Heure\u00a0: 13h00 GMT<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Les grands rassemblements d&rsquo;\u00e9vang\u00e9lisation appartiennent-ils au pass\u00e9&nbsp;? L&rsquo;\u00e9vang\u00e9lisation par la proclamation est-elle morte&nbsp;?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le 23 mai, nous avons \u00e9cout\u00e9 le Dr Desmond Henry et M. Blair Carlson partager des strat\u00e9gies innovantes pour une nouvelle \u00e8re de l&rsquo;\u00e9vang\u00e9lisation. Cet atelier s&rsquo;adressait \u00e0 ceux qui sont passionn\u00e9s par une diffusion plus efficace de l&rsquo;\u00c9vangile et \u00e9tait con\u00e7u pour inspirer et \u00e9quiper l&rsquo;\u00c9glise afin qu&rsquo;elle insuffle une nouvelle vie aux efforts d&rsquo;\u00e9vang\u00e9lisation dans les divers contextes locaux.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Collaborative Action Workshop 2: The Process of Collaborative Action\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ketHnGQ-K54?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px;text-transform:uppercase\"><a href=\"https:\/\/youtu.be\/ketHnGQ-K54\">ATELIER D&rsquo;ACTION COLLABORATIVE 2 (LE PROCESSUS D&rsquo;ACTION COLLABORATIVE)<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date\u00a0: 11 juin 2024<\/li>\n\n\n\n<li>Heure\u00a0: 04h00 GMT<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Lors de ce deuxi\u00e8me des trois ateliers sur l&rsquo;action collaborative, nous avons examin\u00e9, \u00e0 l&rsquo;aide d&rsquo;un processus en trois \u00e9tapes, comment (sont lanc\u00e9es )les initiatives collaboratives( sont lanc\u00e9es). Nous avons \u00e9galement \u00e9tudi\u00e9 la mani\u00e8re d&rsquo;instaurer la confiance, d&rsquo;identifier les parties prenantes et de cr\u00e9er une vision commune. Enfin, l&rsquo;atelier a explor\u00e9 un outil que vous pouvez utiliser lorsque vous vous engagez avec des partenaires de collaboration potentiels. Si vous envisagez de collaborer ou si vous \u00eates d\u00e9j\u00e0 en train de le faire, cet atelier vous fournira des conseils et des outils utiles pour renforcer votre collaboration.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/details>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"onsite\">Participants sur site uniquement<\/h4>\n\n\n\n<details class=\"wp-block-details has-medium-font-size is-layout-flow wp-block-details-is-layout-flow\" open><summary>Voir tous les appels pour les participants sur site<\/summary>\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Congress Logistics Call: Arrive with Confidence (Africa, MENA, Europe, Americas)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/mQrOoeYa-zE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px;text-transform:uppercase\"><a href=\"https:\/\/www.youtube.com\/watch?v=mQrOoeYa-zE\">ORIENTATION DES PARTICIPANTS SUR SITE\u00a0: ARRIVER EN TOUTE CONFIANCE<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date\u00a0: 12 juin 2024<\/li>\n\n\n\n<li>Heure\u00a0: 4h00 &amp; 12h00 GMT<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Vous y trouverez des informations essentielles pour les participants sur site et des conseils sur le voyage, l&rsquo;h\u00e9bergement et l&rsquo;assistance g\u00e9n\u00e9rale afin d&rsquo;assurer une arriv\u00e9e en douceur et en toute confiance au congr\u00e8s.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Onsite Congress Participant Orientation: Collaboration, Networking, and the Congress Programme\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ffOU4sEfL9Y?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h4 class=\"wp-block-heading wp-embed-aspect-16-9 wp-has-aspect-ratio\" style=\"font-size:32px;text-transform:uppercase\"><a href=\"https:\/\/youtu.be\/ffOU4sEfL9Y\">ORIENTATION DES PARTICIPANTS AU CONGR\u00c8S SUR SITE\u00a0: COLLABORATION, MISE EN R\u00c9SEAU ET PROGRAMME DU CONGR\u00c8S<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date\u00a0: 17 juillet 2024<\/li>\n\n\n\n<li>Heure\u00a0: 04h00 et 12h00 GMT<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\">Cette s\u00e9ance offrait, aux participants sur site, un aper\u00e7u approfondi du programme du Congr\u00e8s, ainsi que des informations pr\u00e9cieuses sur les opportunit\u00e9s de r\u00e9seautage et de collaboration. Voici l&rsquo;enregistrement de l\u2019appel de 12h00 GMT le 17 juillet 2024.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/details>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"virtual\">Participants virtuels uniquement<\/h4>\n\n\n\n<details class=\"wp-block-details has-medium-font-size is-layout-flow wp-block-details-is-layout-flow\" open><summary>Voir tous les appels des participants virtuels<\/summary>\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Congress VX Participant Orientation:  Collaboration, Networking and the Congress Programme\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/B08g7MzKx68?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-size:32px;text-transform:uppercase\"><a href=\"https:\/\/youtu.be\/B08g7MzKx68\">ORIENTATION DES PARTICIPANTS AU CONGR\u00c8S VX\u00a0: COLLABORATION, MISE EN R\u00c9SEAU ET PROGRAMME DU CONGR\u00c8S<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date\u00a0: 18 juillet 2024<\/li>\n\n\n\n<li>Heure\u00a0: 04h00 &amp; 12h00 GMT<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cette session offrait une vue d&rsquo;ensemble de l&rsquo;exp\u00e9rience virtuelle du Congr\u00e8s (VX) et fournissait des informations pr\u00e9cieuses sur le r\u00e9seautage et la collaboration en tant que participant virtuel au Quatri\u00e8me congr\u00e8s de Lausanne. Voici l&rsquo;enregistrement de l&rsquo;appel de 12h00 GMT du 18 juillet 2024.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/details>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tous les enregistrements Participants sur site uniquement Participants virtuels uniquement<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6847","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Appels pr\u00e9-congr\u00e8s - The Fourth Lausanne Congress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Appels pr\u00e9-congr\u00e8s - The Fourth Lausanne Congress\" \/>\n<meta property=\"og:description\" content=\"Tous les enregistrements Participants sur site uniquement Participants virtuels uniquement\" \/>\n<meta property=\"og:url\" content=\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/\" \/>\n<meta property=\"og:site_name\" content=\"The Fourth Lausanne Congress\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-07T01:20:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/\",\"name\":\"Appels pr\u00e9-congr\u00e8s - The Fourth Lausanne Congress\",\"isPartOf\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation.jpg\",\"datePublished\":\"2024-06-21T01:02:01+00:00\",\"dateModified\":\"2024-08-07T01:20:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/#primaryimage\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation.jpg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/congress.lausanne.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appels pr\u00e9-congr\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"name\":\"The Fourth Lausanne Congress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\",\"name\":\"The Fourth Lausanne Congress\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"width\":1477,\"height\":266,\"caption\":\"The Fourth Lausanne Congress\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Appels pr\u00e9-congr\u00e8s - The Fourth Lausanne Congress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/","og_locale":"fr_FR","og_type":"article","og_title":"Appels pr\u00e9-congr\u00e8s - The Fourth Lausanne Congress","og_description":"Tous les enregistrements Participants sur site uniquement Participants virtuels uniquement","og_url":"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/","og_site_name":"The Fourth Lausanne Congress","article_modified_time":"2024-08-07T01:20:39+00:00","og_image":[{"url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/","url":"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/","name":"Appels pr\u00e9-congr\u00e8s - The Fourth Lausanne Congress","isPartOf":{"@id":"https:\/\/congress.lausanne.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/#primaryimage"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/#primaryimage"},"thumbnailUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation.jpg","datePublished":"2024-06-21T01:02:01+00:00","dateModified":"2024-08-07T01:20:39+00:00","breadcrumb":{"@id":"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/#primaryimage","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation.jpg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/04\/ongress-Step-7-Participant-Orientation.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/congress.lausanne.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Appels pr\u00e9-congr\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/congress.lausanne.org\/fr\/#website","url":"https:\/\/congress.lausanne.org\/fr\/","name":"The Fourth Lausanne Congress","description":"","publisher":{"@id":"https:\/\/congress.lausanne.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/congress.lausanne.org\/fr\/#organization","name":"The Fourth Lausanne Congress","url":"https:\/\/congress.lausanne.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","width":1477,"height":266,"caption":"The Fourth Lausanne Congress"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/6847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/comments?post=6847"}],"version-history":[{"count":0,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/6847\/revisions"}],"wp:attachment":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/media?parent=6847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6842,"date":"2024-06-06T03:08:59","date_gmt":"2024-06-06T03:08:59","guid":{"rendered":"https:\/\/congress.lausanne.org\/?page_id=6842"},"modified":"2024-08-07T01:20:53","modified_gmt":"2024-08-07T01:20:53","slug":"participants-sur-site","status":"publish","type":"page","link":"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/","title":{"rendered":"Participants sur site"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Participerez-vous sur site \u00e0 S\u00e9oul-Incheon, en Cor\u00e9e du Sud&nbsp;?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Voici ce que vous devez savoir&nbsp;!<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li><a href=\"#registration\">Enregistrement<\/a><\/li>\n\n\n\n<li><a href=\"#logistics\">Logistique<\/a><\/li>\n\n\n\n<li><a href=\"#meals\">Repas<\/a><\/li>\n\n\n\n<li><a href=\"#venue\">Lieu de rencontre<\/a><\/li>\n\n\n\n<li><a href=\"#pre-con-fund\">Programme pr\u00e9alable et Collecte de fonds<\/a><\/li>\n\n\n\n<li><a href=\"#orient\">Appel d\u2019orientation<\/a><\/li>\n\n\n\n<li><a href=\"#help\">Besoin d\u2019aide&nbsp;?<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div id=\"registration\" class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-8fb64bd3 wp-block-group-is-layout-flex\">\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Enregistrement<\/h4>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-92126d18 wp-block-columns-is-layout-flex\" style=\"margin-bottom:0\">\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-cc9e5628e8729570c1d005c67146fbd8 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#e6eaec;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h4 class=\"wp-block-heading has-text-color has-link-color wp-elements-98dc1407ad2c287e7204259a71464748\" style=\"color:#0000ff\"><strong>Arriv\u00e9e<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.5\"><strong>Nous vous conseillons d\u2019arriver le samedi 21 septembre. Le congr\u00e8s commence le dimanche 22 septembre.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous conseillons d\u2019arriver le 21 septembre pour avoir le temps de vous enregistrer \u00e0 l\u2019h\u00f4tel avant le d\u00e9but du congr\u00e8s. Le dimanche 22 septembre, le diner commencera \u00e0 17h00 et sera suivi de la c\u00e9r\u00e9monie d\u2019ouverture \u00e0 18h30. \u00c0 votre arriv\u00e9e, des navettes seront mises \u00e0 disposition les 21 et 22 septembre depuis l\u2019a\u00e9roport. Voir les d\u00e9tails ci-dessous.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-13af67cc367ccac19791e93bbc5a7f3c is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#e6eaec;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h4 class=\"wp-block-heading has-text-color has-link-color wp-elements-f3ee76e993f72449979c8619f99ea21c\" style=\"color:#8100ff\"><strong>Enregistrement sur site<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il est demand\u00e9 \u00e0 tous les participants de s\u2019enregistrer \u00e0 leur arriv\u00e9e sur site avant de participer au congr\u00e8s. L\u2019enregistrement sera ouvert les 21 et 22 septembre de 9h00 \u00e0 18h00, au Songdo Convensia.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#venue\">Se rendre sur site<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-6c9e6ee67dc72f207c83dfe68e115141 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#e6eaec;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h4 class=\"wp-block-heading has-text-color has-link-color wp-elements-745e816653553318054829983ff31c63\" style=\"color:#ff4563\"><strong>D\u00e9part<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.5\"><strong><strong>La c\u00e9r\u00e9monie de cl\u00f4ture s\u2019ach\u00e8vera \u00e0 13h00 le samedi 28 septembre.<\/strong><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Les navettes de d\u00e9part seront mises \u00e0 disposition \u00e0 partir de 13h00 le samedi 28 septembre. Davantage de d\u00e9tails sur les navettes de d\u00e9part seront bient\u00f4t annonc\u00e9s.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n<\/div>\n\n\n\n<div id=\"logistics\" class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-8fb64bd3 wp-block-group-is-layout-flex\">\n<div style=\"height:0px;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-fd0eeb70\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Logistique<\/h4>\n\n\n\n<div style=\"height:0px;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-fd0eeb70\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover alignfull wp-duotone-unset-6\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#7e6f6a;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4522\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel.jpg\" style=\"object-position:15% 50%\" data-object-fit=\"cover\" data-object-position=\"15% 50%\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel.jpg 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel-768x768.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-d2544bf69dbd6e65649b66093d5e50f0\" style=\"letter-spacing:0px;line-height:1;text-transform:uppercase\">Assurance vol et voyage<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous conseillons d\u2019acheter votre billet d\u2019avion pour l\u2019a\u00e9roport international d\u2019Incheon (ICN) avant fin juillet 2024.<\/p>\n\n\n\n<div style=\"height:10.75rem\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/congress.lausanne.org\/fr\/vols\/\" target=\"_blank\" rel=\"noreferrer noopener\">En apprendre davantage<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover alignfull wp-duotone-unset-7\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#786a60;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4508\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-Visa.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-Visa.jpg 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-Visa-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-Visa-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-Visa-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-Visa-768x768.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-5fb99bb1b2124d24084d14fc390ad94b\" style=\"letter-spacing:0px;line-height:1;text-transform:uppercase\">visa<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Certains pays ont besoin d\u2019un visa pour entrer en Cor\u00e9e du Sud. Veuillez v\u00e9rifier les conditions de visa pour votre pays de nationalit\u00e9 et (penser au)tenir compte du temps n\u00e9cessaire pour l\u2019obtenir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La date limite pour demander une lettre num\u00e9rique d\u2019invitation est le 22 ao\u00fbt 2024. La date limite pour les exemplaires papier ou notari\u00e9s est le 31 juillet 2024.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/congress.lausanne.org\/fr\/visa\/\" target=\"_blank\" rel=\"noreferrer noopener\">En apprendre davantage<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover alignfull wp-duotone-unset-8\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#6a6654;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4515\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-hotel.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-hotel.jpg 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-hotel-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-hotel-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-hotel-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-hotel-768x768.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-5819fb1fbfc12d3059295f1f7eb2823b\" style=\"letter-spacing:0px;line-height:1;text-transform:uppercase\">H\u00f4tel et h\u00e9bergement<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez consulter notre page de r\u00e9servation d\u2019h\u00f4tel pour conna\u00eetre les options d\u2019h\u00e9bergement que nous recommandons. Des navettes journali\u00e8res vers le congr\u00e8s seront organis\u00e9es depuis ces h\u00f4tels.<\/p>\n\n\n\n<div style=\"height:11.15rem\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/congress.lausanne.org\/fr\/hotel-et-hebergement\/\" target=\"_blank\" rel=\"noreferrer noopener\">En apprendre davantage<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:17px;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-fd0eeb70\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-cover alignfull wp-duotone-unset-9\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;min-height:50vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#686160;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4487\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME.jpg 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME-768x768.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-0fad48e084d94b32ef88b74705bdb74b\" style=\"letter-spacing:0px;line-height:1;text-transform:uppercase\">Calendrier du programme<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Consultez les grandes lignes du programme du congr\u00e8s et planifiez votre semaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pourrez bient\u00f4t t\u00e9l\u00e9charger l\u2019application Lausanne Gatherings et voir le programme d\u00e9taill\u00e9.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-nowrap is-layout-flex wp-container-core-buttons-is-layout-f4069c65 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\" style=\"letter-spacing:0px\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/congress.lausanne.org\/fr\/programme\/\" style=\"padding-top:24px;padding-right:48px;padding-bottom:24px;padding-left:48px\" target=\"_blank\" rel=\"noreferrer noopener\">Voir le programme<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-cover alignfull is-light wp-duotone-unset-10\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;min-height:50vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#a5abad;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4473\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-LOGISTICS.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-LOGISTICS.jpg 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-LOGISTICS-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-LOGISTICS-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-LOGISTICS-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-LOGISTICS-768x768.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-2f98c855d4df17169d1326a3aad550fe\" style=\"letter-spacing:0px;line-height:1;text-transform:uppercase\">Navettes<\/h4>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-3fe9dde5c5c72fc77d0dbcd34cbfda5c wp-block-paragraph\">Du 21 au 28 septembre des navettes vous transporteront entre l\u2019a\u00e9roport, les h\u00f4tels et le Songdo Convensia.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:5rem\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-nowrap is-layout-flex wp-container-core-buttons-is-layout-f4069c65 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\" style=\"letter-spacing:0px\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/congress.lausanne.org\/fr\/navettes\/\" style=\"padding-top:24px;padding-right:48px;padding-bottom:24px;padding-left:48px\" target=\"_blank\" rel=\"noreferrer noopener\">Voir le navettes<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n<\/div>\n\n\n\n<div id=\"meals\" class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-8fb64bd3 wp-block-group-is-layout-flex\">\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Repas<\/h4>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-92126d18 wp-block-columns-is-layout-flex\" style=\"margin-bottom:0\">\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-ad2ca48a6dd1337d70b660fd179ee241 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#e6eaec;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h4 class=\"wp-block-heading has-text-color has-link-color wp-elements-8d63c17fa9b882ee060c2375daf5f61c\" style=\"color:#0000ff\"><strong>Petit-d\u00e9jeuner<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.5\"><strong>Le petit-d\u00e9jeuner est soit inclus dans la r\u00e9servation de votre h\u00f4tel, soit \u00e0 votre charge.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez noter que le petit-d\u00e9jeuner ne sera pas propos\u00e9 au Songdo Convensia.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-ff92e1170bda6976d87066c450f761a0 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#e6eaec;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h4 class=\"wp-block-heading has-text-color has-link-color wp-elements-11fc99ccee81a5d7acb092f292778680\" style=\"color:#ff4563\"><strong>D\u00e9jeuner<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"line-height:1.5\"><strong>Le d\u00e9jeuner sera fourni chaque jour \u00e0 partir du lundi 23 septembre et jusqu&rsquo;au samedi 28 septembre.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez nous faire part de vos besoins alimentaires par le biais de l&rsquo;enqu\u00eate logistique que vous trouverez en vous connectant <a href=\"http:\/\/journey.lausanne.org\/\">au portail<\/a> (de l&rsquo;)utilisateur.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-ba2a7ef151c3ed0e418801c7c115cc33 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#e6eaec;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h4 class=\"wp-block-heading has-text-color has-link-color wp-elements-f8d4002e3b375e9ef0086b96762d1f92\" style=\"color:#8100ff\"><strong>D\u00eener<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00eener sera servi chaque jour \u00e0 partir du dimanche 22 septembre et jusqu&rsquo;au vendredi 27 septembre.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez nous faire part de vos besoins alimentaires par le biais de l&rsquo;enqu\u00eate logistique que vous trouverez en vous connectant <a href=\"http:\/\/journey.lausanne.org\/\">au portail<\/a> de l&rsquo;utilisateur.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n<\/div>\n\n\n\n<div id=\"venue\" class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-8fb64bd3 wp-block-group-is-layout-flex\">\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<h4 class=\"wp-block-heading\">Lieu de rencontre<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Le Quatri\u00e8me congr\u00e8s de Lausanne se tiendra au Songdo Convensia \u00e0 Incheon, en Cor\u00e9e du Sud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Songdo Convensia<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Convensia, 123 Central-ro, Songdo-dong, Yeonsu-gu, Incheon, Cor\u00e9e du Sud<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.google.com\/maps\/dir\/\/Songdo+Convensia,+Convensia,+123+Central-ro,+Songdo-dong,+Yeonsu-gu,+Incheon,+South+Korea\/@37.3887354,126.6439586,17z\/data=!4m8!4m7!1m0!1m5!1m1!1s0x357b77af40aa3f31:0xdd485945aa3aa3c9!2m2!1d126.6465335!2d37.3887312?entry=ttu\" target=\"_blank\" rel=\"noreferrer noopener\">Obtenir un itin\u00e9raire<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3170.046379378139!2d126.64395857640594!3d37.38873543430264!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x357b77af40aa3f31%3A0xdd485945aa3aa3c9!2sSongdo%20Convensia!5e0!3m2!1sen!2sph!4v1718238751199!5m2!1sen!2sph\" width=\"100%\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n<\/div>\n\n\n\n<div id=\"pre-con-fund\" class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-8fb64bd3 wp-block-group-is-layout-flex\">\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-cover alignfull wp-duotone-unset-11\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;min-height:50vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#686160;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4487\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME.jpg 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PRE-CONGRESS-PROGRAMME-768x768.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-e835f32b87e93d2f8c430e14eb03f03b\" style=\"letter-spacing:0px;line-height:1;text-transform:uppercase\">Programme pr\u00e9alable au congr\u00e8s<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Le mat\u00e9riel de pr\u00e9paration mensuel \u00ab&nbsp;Parcours jusqu\u2019au Congr\u00e8s&nbsp;\u00bb est con\u00e7u pour pr\u00e9parer tous les participants \u00e0 contribuer au Congr\u00e8s. Les participants y d\u00e9couvrent les th\u00e8mes cl\u00e9s du congr\u00e8s, les opportunit\u00e9s de pri\u00e8re et de connexion avant le congr\u00e8s, et bien d&rsquo;autres choses encore&nbsp;!<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-nowrap is-layout-flex wp-container-core-buttons-is-layout-f4069c65 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\" style=\"letter-spacing:0px\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/congress.lausanne.org\/faq\/faq-pre-congress-programme\/\" style=\"padding-top:24px;padding-right:48px;padding-bottom:24px;padding-left:48px\" target=\"_blank\" rel=\"noreferrer noopener\">En apprendre davantage<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-cover alignfull wp-duotone-unset-12\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;min-height:50vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#4c433b;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4480\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PROGRAMME.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PROGRAMME.jpg 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PROGRAMME-300x300.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PROGRAMME-1024x1024.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PROGRAMME-150x150.jpg 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-PROGRAMME-768x768.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-36d1d5b6ce86f304dd6ca3b1baf7240f\" style=\"letter-spacing:0px;line-height:1;text-transform:uppercase\">Collecte de fonds<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9couvrez les ressources pr\u00e9par\u00e9es pour vous aider \u00e0 financer votre voyage \u00e0 S\u00e9oul-Incheon.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:8rem\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-nowrap is-layout-flex wp-container-core-buttons-is-layout-f4069c65 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\" style=\"letter-spacing:0px\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/congress.lausanne.org\/fundraising\/\" style=\"padding-top:24px;padding-right:48px;padding-bottom:24px;padding-left:48px\" target=\"_blank\" rel=\"noreferrer noopener\">Voir les ressources<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n<\/div>\n\n\n\n<div id=\"orient\" class=\"wp-block-group is-vertical is-content-justification-left is-layout-flex wp-container-core-group-is-layout-a411694f wp-block-group-is-layout-flex\">\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n\n\n\n<div class=\"wp-block-columns wp-container-content-9cfa9a5a is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100.6%\">\n<div class=\"wp-block-cover alignfull wp-duotone-unset-13\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;min-height:522px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"737\" class=\"wp-block-cover__image-background wp-image-4501\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/Congress-FAQ-Lausanne-4-Gatherings.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/Congress-FAQ-Lausanne-4-Gatherings.jpg 1920w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/Congress-FAQ-Lausanne-4-Gatherings-300x115.jpg 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/Congress-FAQ-Lausanne-4-Gatherings-1024x393.jpg 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/Congress-FAQ-Lausanne-4-Gatherings-768x295.jpg 768w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/Congress-FAQ-Lausanne-4-Gatherings-1536x590.jpg 1536w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/Congress-FAQ-Lausanne-4-Gatherings-1400x537.jpg 1400w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-de747b09994d976b1777aa2475bb8c75\" style=\"letter-spacing:0px;line-height:1;text-transform:uppercase\">Appel d&rsquo;orientation<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9servez la date de notre prochain appel d&rsquo;orientation&nbsp;: D\u00e9couvrez le programme du congr\u00e8s<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">17 juillet 2024, 04h00GMT et 12h00GMT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous recevrez bient\u00f4t le lien d&rsquo;inscription dans votre bo\u00eete aux lettres \u00e9lectronique.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/congress.lausanne.org\/fr\/appels-pre-congres\/\" target=\"_blank\" rel=\"noreferrer noopener\">Voir les appels pr\u00e9c\u00e9dents<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n<\/div>\n\n\n\n<div id=\"help\" class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-8fb64bd3 wp-block-group-is-layout-flex\">\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-c559bc2c9fd6f05452e5f8c1d770833d is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#e6eaec;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h4 class=\"wp-block-heading has-text-color has-link-color wp-elements-b4943d3549aeaede5f26e16176abffba\" style=\"color:#8100ff\"><strong>Besoin d&rsquo;aide&nbsp;?<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veuillez consulter notre <a href=\"https:\/\/congress.lausanne.org\/faq\/\">Foire aux questions<\/a> ou contacter notre \u00e9quipe \u00e0 l&rsquo;adresse&nbsp;: <a href=\"mailto:help@lausanne.org\">help@lausanne.org<\/a>, et nous vous r\u00e9pondrons d\u00e8s que possible.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/congress.lausanne.org\/faq\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aller \u00e0 la FAQ<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"mailto:help@lausanne.org\" target=\"_blank\" rel=\"noreferrer noopener\">Envoyez-nous un courriel       <\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-370e7c34\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Participerez-vous sur site \u00e0 S\u00e9oul-Incheon, en Cor\u00e9e du Sud&nbsp;? Voici ce que vous devez savoir&nbsp;! Enregistrement Arriv\u00e9e Nous vous conseillons d\u2019arriver le samedi 21 septembre. Le congr\u00e8s commence le dimanche 22 septembre. Nous vous conseillons d\u2019arriver le 21 septembre pour avoir le temps de vous enregistrer \u00e0 l\u2019h\u00f4tel avant&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6842","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Participants sur site - The Fourth Lausanne Congress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Participants sur site - The Fourth Lausanne Congress\" \/>\n<meta property=\"og:description\" content=\"Participerez-vous sur site \u00e0 S\u00e9oul-Incheon, en Cor\u00e9e du Sud&nbsp;? Voici ce que vous devez savoir&nbsp;! Enregistrement Arriv\u00e9e Nous vous conseillons d\u2019arriver le samedi 21 septembre. Le congr\u00e8s commence le dimanche 22 septembre. Nous vous conseillons d\u2019arriver le 21 septembre pour avoir le temps de vous enregistrer \u00e0 l\u2019h\u00f4tel avant...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/\" \/>\n<meta property=\"og:site_name\" content=\"The Fourth Lausanne Congress\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-07T01:20:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/\",\"name\":\"Participants sur site - The Fourth Lausanne Congress\",\"isPartOf\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel.jpg\",\"datePublished\":\"2024-06-06T03:08:59+00:00\",\"dateModified\":\"2024-08-07T01:20:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/#primaryimage\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel.jpg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/congress.lausanne.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participants sur site\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"name\":\"The Fourth Lausanne Congress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\",\"name\":\"The Fourth Lausanne Congress\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"width\":1477,\"height\":266,\"caption\":\"The Fourth Lausanne Congress\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Participants sur site - The Fourth Lausanne Congress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/","og_locale":"fr_FR","og_type":"article","og_title":"Participants sur site - The Fourth Lausanne Congress","og_description":"Participerez-vous sur site \u00e0 S\u00e9oul-Incheon, en Cor\u00e9e du Sud&nbsp;? Voici ce que vous devez savoir&nbsp;! Enregistrement Arriv\u00e9e Nous vous conseillons d\u2019arriver le samedi 21 septembre. Le congr\u00e8s commence le dimanche 22 septembre. Nous vous conseillons d\u2019arriver le 21 septembre pour avoir le temps de vous enregistrer \u00e0 l\u2019h\u00f4tel avant...","og_url":"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/","og_site_name":"The Fourth Lausanne Congress","article_modified_time":"2024-08-07T01:20:53+00:00","og_image":[{"url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/","url":"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/","name":"Participants sur site - The Fourth Lausanne Congress","isPartOf":{"@id":"https:\/\/congress.lausanne.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/#primaryimage"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/#primaryimage"},"thumbnailUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel.jpg","datePublished":"2024-06-06T03:08:59+00:00","dateModified":"2024-08-07T01:20:53+00:00","breadcrumb":{"@id":"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/#primaryimage","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel.jpg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-FAQ-Logistics-travel.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/congress.lausanne.org\/fr\/participants-sur-site\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/congress.lausanne.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Participants sur site"}]},{"@type":"WebSite","@id":"https:\/\/congress.lausanne.org\/fr\/#website","url":"https:\/\/congress.lausanne.org\/fr\/","name":"The Fourth Lausanne Congress","description":"","publisher":{"@id":"https:\/\/congress.lausanne.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/congress.lausanne.org\/fr\/#organization","name":"The Fourth Lausanne Congress","url":"https:\/\/congress.lausanne.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","width":1477,"height":266,"caption":"The Fourth Lausanne Congress"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/6842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/comments?post=6842"}],"version-history":[{"count":0,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/6842\/revisions"}],"wp:attachment":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/media?parent=6842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4808,"date":"2024-05-15T09:15:10","date_gmt":"2024-05-15T09:15:10","guid":{"rendered":"https:\/\/congress.lausanne.org\/?page_id=4808"},"modified":"2024-05-29T01:22:36","modified_gmt":"2024-05-29T01:22:36","slug":"parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres","status":"publish","type":"page","link":"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/","title":{"rendered":"Parcours Monde du travail et Groupes facultatifs d\u2019int\u00e9r\u00eat, pendant le congr\u00e8s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Du lundi 23 septembre au vendredi 27 septembre, les participants pourront participer \u00e0 des parcours et groupes d\u2019int\u00e9r\u00eat facultatifs, entre 13.00 et 15.00. Voir <a href=\"https:\/\/congress.lausanne.org\/schedule\/\">l\u2019emploi du temps<\/a> pour le contexte g\u00e9n\u00e9ral. Dans un prochain questionnaire, il vous sera demand\u00e9 de faire des choix si vous souhaitez y participer.<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-stretch is-layout-flex wp-container-core-group-is-layout-8fb64bd3 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-cover alignfull wp-duotone-unset-14\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;min-height:50vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#423e45;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4842\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace.png\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace.png 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace-300x300.png 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace-1024x1024.png 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace-150x150.png 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace-768x768.png 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-2a9edde24b0e59a5cfc7beb403854b02\" style=\"font-size:34px;letter-spacing:0px;line-height:1;text-transform:uppercase\">PAROURS MONDE DU TRAVAIL<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lundi, mardi et jeudi de 13.15 \u00e0 14.45<br>Mercredi de 13.15 \u00e0 17.00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destin\u00e9 aux personnes int\u00e9ress\u00e9es par, ou d\u00e9j\u00e0 impliqu\u00e9es dans, les r\u00e9seaux Minist\u00e8re dans le milieu du travail, Mission par les affaires, Faiseurs de tente et Minist\u00e8res et \u00e9ducateurs universitaires (RMEU).<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-nowrap is-layout-flex wp-container-core-buttons-is-layout-f4069c65 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\" style=\"letter-spacing:0px\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/congress.lausanne.org\/?page_id=4566\" style=\"padding-top:24px;padding-right:48px;padding-bottom:24px;padding-left:48px\">En apprendre davantage<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-cover alignfull is-light wp-duotone-unset-15\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;min-height:50vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#b5b9bb;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4828\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-north-korea.png\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-north-korea.png 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-north-korea-300x300.png 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-north-korea-1024x1024.png 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-north-korea-150x150.png 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-north-korea-768x768.png 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-50a055495c8c2d622a40c68fcde51753\" style=\"font-size:34px;letter-spacing:0px;line-height:1;text-transform:uppercase\">GROUPE D\u2019INT\u00c9R\u00caT COR\u00c9E DU NORD<\/h2>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-c768a44fd6f7ca9b33b1c747c59fa5c0 wp-block-paragraph\">Mardi, mercredi, jeudi de 13.30 \u00e0 14.30<\/p>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-56a0f6c8f7443f6d67e82fa465c66e37 wp-block-paragraph\">Destin\u00e9 aux personnes souhaitant participer \u00e0 des activit\u00e9s \u0153uvrant pour la paix et la r\u00e9conciliation en Cor\u00e9e du Nord, ou souhaitant mobiliser d\u2019autres personnes.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-nowrap is-layout-flex wp-container-core-buttons-is-layout-f4069c65 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\" style=\"letter-spacing:0px\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/congress.lausanne.org\/?page_id=4602\" style=\"padding-top:24px;padding-right:48px;padding-bottom:24px;padding-left:48px\">En apprendre davantage<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:2em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-42fb7c7f\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-cover alignfull wp-duotone-unset-16\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;min-height:50vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#423e45;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4821\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-issue-networks.png\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-issue-networks.png 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-issue-networks-300x300.png 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-issue-networks-1024x1024.png 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-issue-networks-150x150.png 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-issue-networks-768x768.png 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-2dbb57182a234202a6a498dde898ed6f\" style=\"font-size:34px;letter-spacing:0px;line-height:1;text-transform:uppercase\">R\u00c9SEAUX TH\u00c9MATIQUES<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lundi de 13.20 \u00e0 14.30<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019occasion pour vous de vous impliquer dans un r\u00e9seau th\u00e9matique.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-nowrap is-layout-flex wp-container-core-buttons-is-layout-f4069c65 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\" style=\"letter-spacing:0px\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/lausanne.org\/issue-networks\" style=\"padding-top:24px;padding-right:48px;padding-bottom:24px;padding-left:48px\">En apprendre davantage<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-cover alignfull wp-duotone-unset-17\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;min-height:50vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background-color:#423e45;background:linear-gradient(135deg,rgb(0,3,255) 0%,rgb(255,170,159) 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"1400\" class=\"wp-block-cover__image-background wp-image-4835\" alt=\"\" src=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-regional-networks.png\" data-object-fit=\"cover\" srcset=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-regional-networks.png 1400w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-regional-networks-300x300.png 300w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-regional-networks-1024x1024.png 1024w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-regional-networks-150x150.png 150w, https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-regional-networks-768x768.png 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-left\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-2f471073 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-left has-white-color has-text-color has-link-color wp-elements-6beeee92ce65925b28fa6c2bb80d100c\" style=\"font-size:34px;letter-spacing:0px;line-height:1;text-transform:uppercase\">R\u00c9SEAUX R\u00c9GIONAUX<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vendredi de 13.30 \u00e0 14.30<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019occasion pour vous de vous impliquer dans un r\u00e9seau r\u00e9gional.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-nowrap is-layout-flex wp-container-core-buttons-is-layout-f4069c65 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\" style=\"letter-spacing:0px\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/lausanne.org\/network-type\/regions\" style=\"padding-top:24px;padding-right:48px;padding-bottom:24px;padding-left:48px\">En apprendre davantage<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:2em;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-42fb7c7f\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Du lundi 23 septembre au vendredi 27 septembre, les participants pourront participer \u00e0 des parcours et groupes d\u2019int\u00e9r\u00eat facultatifs, entre 13.00 et 15.00. Voir l\u2019emploi du temps pour le contexte g\u00e9n\u00e9ral. Dans un prochain questionnaire, il vous sera demand\u00e9 de faire des choix si vous souhaitez y participer.<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4808","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Parcours Monde du travail et Groupes facultatifs d\u2019int\u00e9r\u00eat, pendant le congr\u00e8s - The Fourth Lausanne Congress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parcours Monde du travail et Groupes facultatifs d\u2019int\u00e9r\u00eat, pendant le congr\u00e8s - The Fourth Lausanne Congress\" \/>\n<meta property=\"og:description\" content=\"Du lundi 23 septembre au vendredi 27 septembre, les participants pourront participer \u00e0 des parcours et groupes d\u2019int\u00e9r\u00eat facultatifs, entre 13.00 et 15.00. Voir l\u2019emploi du temps pour le contexte g\u00e9n\u00e9ral. Dans un prochain questionnaire, il vous sera demand\u00e9 de faire des choix si vous souhaitez y participer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/\" \/>\n<meta property=\"og:site_name\" content=\"The Fourth Lausanne Congress\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-29T01:22:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/\",\"name\":\"Parcours Monde du travail et Groupes facultatifs d\u2019int\u00e9r\u00eat, pendant le congr\u00e8s - The Fourth Lausanne Congress\",\"isPartOf\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace.png\",\"datePublished\":\"2024-05-15T09:15:10+00:00\",\"dateModified\":\"2024-05-29T01:22:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/#primaryimage\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace.png\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/congress.lausanne.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parcours Monde du travail et Groupes facultatifs d\u2019int\u00e9r\u00eat, pendant le congr\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#website\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"name\":\"The Fourth Lausanne Congress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#organization\",\"name\":\"The Fourth Lausanne Congress\",\"url\":\"https:\/\/congress.lausanne.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"contentUrl\":\"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg\",\"width\":1477,\"height\":266,\"caption\":\"The Fourth Lausanne Congress\"},\"image\":{\"@id\":\"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parcours Monde du travail et Groupes facultatifs d\u2019int\u00e9r\u00eat, pendant le congr\u00e8s - The Fourth Lausanne Congress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/","og_locale":"fr_FR","og_type":"article","og_title":"Parcours Monde du travail et Groupes facultatifs d\u2019int\u00e9r\u00eat, pendant le congr\u00e8s - The Fourth Lausanne Congress","og_description":"Du lundi 23 septembre au vendredi 27 septembre, les participants pourront participer \u00e0 des parcours et groupes d\u2019int\u00e9r\u00eat facultatifs, entre 13.00 et 15.00. Voir l\u2019emploi du temps pour le contexte g\u00e9n\u00e9ral. Dans un prochain questionnaire, il vous sera demand\u00e9 de faire des choix si vous souhaitez y participer.","og_url":"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/","og_site_name":"The Fourth Lausanne Congress","article_modified_time":"2024-05-29T01:22:36+00:00","og_image":[{"url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/","url":"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/","name":"Parcours Monde du travail et Groupes facultatifs d\u2019int\u00e9r\u00eat, pendant le congr\u00e8s - The Fourth Lausanne Congress","isPartOf":{"@id":"https:\/\/congress.lausanne.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/#primaryimage"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/#primaryimage"},"thumbnailUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace.png","datePublished":"2024-05-15T09:15:10+00:00","dateModified":"2024-05-29T01:22:36+00:00","breadcrumb":{"@id":"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/#primaryimage","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace.png","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/05\/congress-optional-track-workplace.png"},{"@type":"BreadcrumbList","@id":"https:\/\/congress.lausanne.org\/fr\/parcours-monde-du-travail-et-groupes-facultatifs-dinteret-pendant-le-congres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/congress.lausanne.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Parcours Monde du travail et Groupes facultatifs d\u2019int\u00e9r\u00eat, pendant le congr\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/congress.lausanne.org\/fr\/#website","url":"https:\/\/congress.lausanne.org\/fr\/","name":"The Fourth Lausanne Congress","description":"","publisher":{"@id":"https:\/\/congress.lausanne.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/congress.lausanne.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/congress.lausanne.org\/fr\/#organization","name":"The Fourth Lausanne Congress","url":"https:\/\/congress.lausanne.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","contentUrl":"https:\/\/congress.lausanne.org\/wp-content\/uploads\/2024\/01\/the-fourth-lausanne-congress-logo-blue-landscape.svg","width":1477,"height":266,"caption":"The Fourth Lausanne Congress"},"image":{"@id":"https:\/\/congress.lausanne.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/4808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/comments?post=4808"}],"version-history":[{"count":0,"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/pages\/4808\/revisions"}],"wp:attachment":[{"href":"https:\/\/congress.lausanne.org\/fr\/wp-json\/wp\/v2\/media?parent=4808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}]